{"id":7854,"date":"2025-06-23T16:07:24","date_gmt":"2025-06-23T20:07:24","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?post_type=dt_portfolio&#038;p=7854"},"modified":"2025-06-23T16:07:24","modified_gmt":"2025-06-23T20:07:24","slug":"letras-monumentales-la-lisera","status":"publish","type":"dt_portfolio","link":"https:\/\/www.costachinchorro.cl\/ccc23\/proyecto\/letras-monumentales-la-lisera\/","title":{"rendered":"Letras Monumentales La Lisera"},"content":{"rendered":"<section class=\"wpb-content-wrapper\"><p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Letras Monumentales La Lisera&#8221;][vc_column_text]La instalaci\u00f3n de las letras tur\u00edsticas viene a poner en valor la playa la Lisera, siendo un atractivo tur\u00edstico para nuestros usuarios y los tur\u00edstas que vienen a la ciudad de paso.<\/p>\n<p>En Ejecuci\u00f3n<\/p>\n<p>Subvenci\u00f3n Municipal: $12.000.000[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;]        <style>#mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-slidenav .vc_icon_element-icon { font-size: 30px; }#mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-slidenav { color: rgba(183,183,183,0.7); }\n             #mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-dotnav > * > * {\n                background-color: rgba(183,183,183,0.7); \n\t            opacity: 0.5;\n                width: 30px;\n                height: 30px;\n                cursor: pointer;\n            }\n            \n            #mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-dotnav > * > :hover {\n                opacity: 0.7;\n            }\n            \n\t        #mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-dotnav > .mdp-active > * { \n\t            background-color: rgba(183,183,183,0.7); \n\t            opacity: 1; \n            }\n        #mdp-glider-slideset-d751713988987e9331980363e24189ce .mdp-glider-slideset-container .mdp-slideset > li { display: flex; align-items: ; }.mdp-glider-slideset-item-d751713988987e9331980363e24189ce > div { height: auto; overflow: hidden; }.mdp-glider-slideset-item-d751713988987e9331980363e24189ce > div { display: flex; align-items: ; }<\/style>        <div class=\"mdp-glider-slideset mdp-slidenav-position-center\" id=\"mdp-glider-slideset-d751713988987e9331980363e24189ce\">\n            <div class=\"mdp-glider-slideset-container \" data-mdp-slideset=\"{small: '1', medium: '2', large: '3', animation: 'fade', duration: 500, autoplay: false, pauseOnHover: false}\">\n                <div class=\"mdp-slidenav-position\">\n                    <ul class=\"mdp-grid mdp-slideset mdp-flex-center mdp-grid-default\">\n\t                    <li class=\"mdp-glider-slidesetslide mdp-glider-slideset-item-d751713988987e9331980363e24189ce\"><div class=\"mdp-flex mdp-flex-center mdp-flex-middle\"><div class=\"mdp-glider-content\"><p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-7855\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2025\/06\/IMG-20181208-WA0019.jpg\" alt=\"\" width=\"1280\" height=\"853\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2025\/06\/IMG-20181208-WA0019.jpg 1280w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2025\/06\/IMG-20181208-WA0019-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2025\/06\/IMG-20181208-WA0019-1024x682.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2025\/06\/IMG-20181208-WA0019-768x512.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><\/p>\n<\/div><\/div><\/li>                    <\/ul>\n\n                                    <\/div>\n\n                \n            <\/div>\n        <\/div>\n\n        [\/vc_column][\/vc_row]<\/p>\n<\/section>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column width=&#8221;1\/2&#8243;][vc_custom_heading text=&#8221;Letras Monumentales La Lisera&#8221;][vc_column_text]La instalaci\u00f3n de las letras tur\u00edsticas viene a poner en valor la playa la Lisera, siendo un atractivo tur\u00edstico para nuestros usuarios y los tur\u00edstas que vienen a la ciudad de paso. En Ejecuci\u00f3n Subvenci\u00f3n Municipal: $12.000.000[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":2,"featured_media":7855,"comment_status":"closed","ping_status":"closed","template":"","dt_portfolio_category":[56],"dt_portfolio_tags":[],"class_list":["post-7854","dt_portfolio","type-dt_portfolio","status-publish","has-post-thumbnail","hentry","dt_portfolio_category-gestion-de-sitios","dt_portfolio_category-56","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio\/7854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/dt_portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=7854"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio\/7854\/revisions"}],"predecessor-version":[{"id":7856,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio\/7854\/revisions\/7856"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/7855"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=7854"}],"wp:term":[{"taxonomy":"dt_portfolio_category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio_category?post=7854"},{"taxonomy":"dt_portfolio_tags","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/dt_portfolio_tags?post=7854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}