{"id":1048,"date":"2019-04-05T18:15:12","date_gmt":"2019-04-05T21:15:12","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=1048"},"modified":"2019-04-05T18:15:12","modified_gmt":"2019-04-05T21:15:12","slug":"cifras-positivas-arroja-borde-costero-sur-en-reciente-temporada-estival-arica","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/cifras-positivas-arroja-borde-costero-sur-en-reciente-temporada-estival-arica\/","title":{"rendered":"Cifras positivas arroja borde costero sur en reciente temporada estival Arica"},"content":{"rendered":"<p><em><strong>Municipalidad y Corporaci\u00f3n Municipal Costa Chinchorro entregaron datos duros acerca de la visitaci\u00f3n en Cuevas de Anzota, El Laucho y La Lisera<\/strong>.<\/em><\/p>\n<p style=\"text-align: justify;\">Datos como que m\u00e1s de 400 mil personas disfrutaron de las playas El Laucho y la Lisera durante toda la temporada estival, o que en el mismo periodo 54 mil 50 personas visitaron el patrimonio natural Cuevas de Anzota, son parte de la informaci\u00f3n entregada por el alcalde de Arica, Gerardo Esp\u00edndola, acompa\u00f1ado de los concejales Jorge Mollo y Patricio G\u00e1lvez directores de servicio y de la Corporaci\u00f3n Municipal Costa Chinchorro.<\/p>\n<p style=\"text-align: justify;\">Los datos fueron procesados por la Corporaci\u00f3n Municipal Costa Chinchorro durante la temporada estival mediante el levantamiento de datos a trav\u00e9s de la aplicaci\u00f3n de las declaraciones de responsabilidad en Anzota, y por medici\u00f3n de ocupaci\u00f3n espacial en el Laucho y la Lisera a trav\u00e9s de aforo determinado.<\/p>\n<p style=\"text-align: justify;\">\u201cLa creaci\u00f3n de la Corporaci\u00f3n fue una decisi\u00f3n pol\u00edtica que tomamos como municipalidad, hoy podemos cuantificar los resultados y de este modo aportar entregar inteligencia al mercado y a la industria tur\u00edstica, para \u00a0la toma de decisiones no s\u00f3lo como comuna, sino tambi\u00e9n como regi\u00f3n\u201d, destac\u00f3 el alcalde de Arica.<\/p>\n<p style=\"text-align: justify;\">\u201cEstamos haciendo una medici\u00f3n de qui\u00e9nes son, de d\u00f3nde provienen, que buscan, hoy tenemos cifras importantes, nos visitaron de m\u00e1s de 50 pa\u00edses, cifras que antes no se ten\u00eda. Antes era bastante precario, ahora estamos colocando m\u00e1s profesionalismo a estas acciones, m\u00e1s m\u00e9trica, lo que va a permitir a nivel local, regional e incluso nacional, tomar decisiones estrat\u00e9gicas y focalizadas al momento de realizar inversiones tur\u00edsticas en la ciudad\u201d, agreg\u00f3 la autoridad comunal.<\/p>\n<p style=\"text-align: justify;\">Por otra parte, el alcalde destac\u00f3 que tanto el balneario La Lisera como el Laucho se mantendr\u00e1n habilitadas durante el a\u00f1o. \u00a0\u201cLa playa El Laucho por primera vez va a estar abierta los 12 meses, junto a la Lisera. Somos la \u00fanica comuna en Chile que tiene dos playas habilitadas durante todo el a\u00f1o\u201d. Para que se pueda habilitar una playa se debe cumplir con protecci\u00f3n y con el tema de seguridad, contar con ba\u00f1os habilitados, salvavidas y tener la l\u00ednea de seguridad de playa, a eso se suman los espacios de servicios y productos que activan peque\u00f1os emprendedores.<\/p>\n<p style=\"text-align: justify;\">CIFRAS<\/p>\n<p style=\"text-align: justify;\">Por su parte, el director ejecutivo de la Corporaci\u00f3n Municipal Costa Chinchorro, Ay\u00fa San Mart\u00edn Li, destac\u00f3 el trabajo\u00a0 mancomunado que se viene realizando en conjunto con la Municipalidad y comunidad. \u201cEstamos cerrando un verano con una cuantificaci\u00f3n de 406 mil personas que visitaron El Laucho y La Lisera durante la temporada; y con 54 mil 50 visitas a Anzota, ademas de generar espacios para emprendedores locales que aportaron con sus servicios y productos. Lo importante de las cifras es que entre otros , ya sabemos que de los 54 mil visitantes en el caso de Anzota, el 56 por ciento: \u00a030.654 \u00a0son turistas que nos visitan desde el pais o del extranjero, ademas sabemos sus motivaciones de viaje y otros datos que nos permiten un an\u00e1lisis muy importante de nuestros visitantes y avanzar hacia un instrumento mas preciso como un Observatorio Tur\u00edstico o un espacio para an\u00e1lisis de flujo, lo cual nos permitir\u00e1 aportar a los peque\u00f1os y grandes emprendimientos, mejorando nuestra respuesta respecto de las expectativas de nuestros turistas\u201d, enfatizo el Director Ejecutivo.<\/p>\n<p style=\"text-align: justify;\">Por su parte, el director de Turismo, Benedicto Colina, destac\u00f3 la importancia de contar con datos fidedignos para la construcci\u00f3n del destino.\u00a0 \u201cDefinitivamente conocer no s\u00f3lo aspectos cualitativos, sino tambi\u00e9n cuantitativos nos permitir\u00e1 postular con mejor propiedad frente a la adquisici\u00f3n de recursos de distintos centros de financiamiento como es el gobierno regional y el gobierno central donde tenemos que presentar acciones que logren atraer a las personas\u201d, se\u00f1al\u00f3<\/p>\n<p style=\"text-align: justify;\">En tanto, el concejal Jorge Mollo, destac\u00f3 la importancia de la creaci\u00f3n de la Corporaci\u00f3n Municipal Costa Chinchorro como una herramienta que permita potenciar tur\u00edsticamente la ciudad y la regi\u00f3n\u00a0 \u201cLa municipalidad llev\u00f3 a la Comisi\u00f3n de Turismo y Borde Costero la posibilidad de crear una Corporaci\u00f3n,\u00a0 y terminamos apoyando la Corporaci\u00f3n y precisamente lo que busc\u00e1bamos con esto \u00a0era entregar consistencia a la actividad tur\u00edstica, entregar datos como los que est\u00e1 entregando el director de la Corporaci\u00f3n,\u00a0 que nos permite darle a los actores de la ciudad la capacidad de tomar buenas decisiones y por ende fomentar la productividad de la comuna\u201d, indic\u00f3 el edil.<\/p>\n<p style=\"text-align: justify;\">En tanto, el concejal Patricio G\u00e1lvez hizo un \u00e9nfasis en que hoy la ciudad cuente con playas habilitadas durante todo el a\u00f1o. \u201cTenemos dos playas habilitadas todo el a\u00f1o, con esto se hace realidad lo de Arica \u201cCiudad de la eterna primavera\u201d, y ahora nosotros tenemos que empezar a generar nuevas instancias para que el mundo deportivo nacional y tambi\u00e9n a nivel internacional vengan a practicar deporte a nuestra ciudad. A hacer \u00a0de Arica un verdadero polo deportivo\u201d, puntualiz\u00f3.<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 50%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-1048 gallery-columns-2 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"\" data-dt-img-description=\"\" data-large_image_width=\"1200\" data-large_image_height=\"800\"href='https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/04\/DSF4023.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>Municipalidad y Corporaci\u00f3n Municipal Costa Chinchorro entregaron datos duros acerca de la visitaci\u00f3n en Cuevas de Anzota, El Laucho y La Lisera. Datos como que m\u00e1s de 400 mil personas disfrutaron de las playas El Laucho y la Lisera durante toda la temporada estival, o que en el mismo periodo 54 mil 50 personas visitaron&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1049,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-1048","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/1048","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=1048"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/1048\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/1049"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=1048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=1048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=1048"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=1048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}