{"id":1269,"date":"2019-08-08T10:37:57","date_gmt":"2019-08-08T14:37:57","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=1269"},"modified":"2019-08-08T10:37:57","modified_gmt":"2019-08-08T14:37:57","slug":"avanzan-obras-de-recuperacion-de-mejora-fiscal-norte-de-la-lisera","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/avanzan-obras-de-recuperacion-de-mejora-fiscal-norte-de-la-lisera\/","title":{"rendered":"Avanzan obras de recuperaci\u00f3n de mejora fiscal norte de La Lisera"},"content":{"rendered":"<p style=\"text-align: justify;\">En pleno proceso de recuperaci\u00f3n de la infraestructura existente\u00a0 y habilitaci\u00f3n de cierros y puntos el\u00e9ctricos; y otros trabajos se encuentra la empresa contratista encargada de las obras de la mejora fiscal norte\u00a0 de la playa La Lisera (conocida como Ex Varos), as\u00ed lo confirm\u00f3 el director ejecutivo de la Corporaci\u00f3n Municipal Costa Chinchorro, Ay\u00fa San Mart\u00edn, quien recorri\u00f3 las obras para verificar el avance de las mismas y la protecci\u00f3n y seguridad que se est\u00e1 dando al sector para evitar que vuelva a ser sujeto de incivilidades.<\/p>\n<p style=\"text-align: justify;\">\u201cAc\u00e1 estamos recuperando un espacio que hab\u00eda estado mal utilizado por personas que lo hab\u00edan ocupado ilegalmente y adem\u00e1s lo hab\u00edan destrozados transform\u00e1ndolo en una letrina. Ya llevamos dos meses aproximadamente en la recuperaci\u00f3n de este espacio para ser utilizado de manera distinta\u201d, indic\u00f3 San Mart\u00edn,<\/p>\n<p style=\"text-align: justify;\">El ejecutivo agreg\u00f3 que en este espacio se contempla realizar activaciones culturales, deportivas y un espacio comunitario para realizar actividades al lado de la costa. Adem\u00e1s, se contempla que el espacio contemple un sector para informaci\u00f3n tur\u00edstica, un centro de operaciones y oficinas que permitan cautelar que el lugar no vuelva a ser malutilizado.<\/p>\n<p style=\"text-align: justify;\">Las obras contemplan cambio de sombreadero, pintura de muros interiores y exteriores, reposici\u00f3n de la instalaci\u00f3n sanitaria, lo cual contempla cambio de caler\u00edas, artefactos y grifer\u00eda, restauraci\u00f3n del piso existente, reposici\u00f3n y normalizaci\u00f3n de la instalaci\u00f3n el\u00e9ctricas. Y las obras estar\u00edan terminadas las primeras semanas de septiembre<\/p>\n<p style=\"text-align: justify;\">RECUPERACI\u00d3N ESPACIO<\/p>\n<p style=\"text-align: justify;\">Cabe mencionar que la primera semana de mayo de este a\u00f1o \u00a0una acci\u00f3n conjunta entre la Gobernaci\u00f3n Provincial de Arica, la Gobernaci\u00f3n Mar\u00edtima y la Municipalidad de Arica permiti\u00f3 el desalojo de la mejora fiscal norte de Playa Lisera, la cual se encontraba ocupada de forma ilegal y en p\u00e9simas condiciones de sanidad.<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-1269 gallery-columns-3 gallery-size-medium'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover rollover-zoom dt-pswp-item\" title=\"\" data-dt-img-description=\"\" data-large_image_width=\"1200\" data-large_image_height=\"800\"href='https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2019\/08\/DSCF1015.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl>\n\t\t\t\t<br style='clear: both' \/>\n\t\t\t<\/div>\n\n","protected":false},"excerpt":{"rendered":"<p>En pleno proceso de recuperaci\u00f3n de la infraestructura existente\u00a0 y habilitaci\u00f3n de cierros y puntos el\u00e9ctricos; y otros trabajos se encuentra la empresa contratista encargada de las obras de la mejora fiscal norte\u00a0 de la playa La Lisera (conocida como Ex Varos), as\u00ed lo confirm\u00f3 el director ejecutivo de la Corporaci\u00f3n Municipal Costa Chinchorro, Ay\u00fa&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1271,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-1269","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/1269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=1269"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/1269\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/1271"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=1269"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=1269"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=1269"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=1269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}