{"id":2621,"date":"2020-07-29T08:00:48","date_gmt":"2020-07-29T12:00:48","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=2621"},"modified":"2020-07-29T08:00:48","modified_gmt":"2020-07-29T12:00:48","slug":"llamado-a-postulacion-prestamo-bicicletas-electricas-para-emprendedores-de-arica-tercera-fecha","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/llamado-a-postulacion-prestamo-bicicletas-electricas-para-emprendedores-de-arica-tercera-fecha\/","title":{"rendered":"Llamado a postulaci\u00f3n pr\u00e9stamo bicicletas el\u00e9ctricas para emprendedores de Arica (Tercera fecha)"},"content":{"rendered":"<div class=\"page\" title=\"Page 2\">\n<div class=\"layoutArea\">\n<div class=\"column\">\n<p style=\"text-align: justify;\">Con el fin de apoyar a las mipymes arique\u00f1as ante los desaf\u00edos que han surgido por la pandemia del COVID 19, la Corporaci\u00f3n Municipal de Fomento Productivo Costa Chinchorro, abre llamado a postular a \u201cSistema de pr\u00e9stamos de bicicletas el\u00e9ctricas\u201d con el fin de que los emprendedores arique\u00f1os, que cumplan con los requisitos, puedan postular y adjudicarse hasta tres unidades para realizar los despachos de sus ventas, disminuyendo los costos de traslados y tiempos de entrega, contribuyendo paralelamente, con el cuidado de nuestro medio ambiente al utilizar un transporte ecol\u00f3gico, r\u00e1pido y eficiente.<\/p>\n<p style=\"text-align: justify;\">Invitamos a todos los emprendedores de nuestra ciudad, sean personas naturales o jur\u00eddicas, a postular a este sistema de pr\u00e9stamo, enviando su postulaci\u00f3n con todos los antecedentes solicitados a nuestro correo <a href=\"mailto:contacto@costachinchorro.cl\">contacto@costachinchorro.cl<\/a>.<\/p>\n<p style=\"text-align: justify;\">El n\u00famero de unidades es limitado, y su adjudicaci\u00f3n, se determinar\u00e1 por el cumplimiento de los requisitos, el orden de recepci\u00f3n de las postulaciones y la disponibilidad de unidades.<\/p>\n<p style=\"text-align: justify;\">En caso de no haber postulantes que cumplan con los requisitos, la Corporaci\u00f3n Municipal, se reserva el derecho de no adjudicar.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<\/div>\n<style type=\"text\/css\" data-type=\"the7_shortcodes-inline-css\">#default-btn-5f052448dc711e31fe121d4953dd3306.ico-right-side > i {\n  margin-right: 0px;\n  margin-left: 8px;\n}\n#default-btn-5f052448dc711e31fe121d4953dd3306 > i {\n  margin-right: 8px;\n}\n<\/style><a href=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2020\/07\/Llamado-Bicicletas-electricas-julio-agosto-2020.pdf\" class=\"default-btn-shortcode dt-btn dt-btn-l link-hover-off \" id=\"default-btn-5f052448dc711e31fe121d4953dd3306\"><span>Descargar Bases de llamado a postulaci\u00f3n<\/span><\/a>\n<p>&nbsp;<\/p>\n<h4>Cronograma del proceso de postulaci\u00f3n, evaluaci\u00f3n y selecci\u00f3n<\/h4>\n<p><strong>Apertura: 29 de julio de 2020.<\/strong><\/p>\n<p><strong>Cierre: 06 de agosto de 2020.<\/strong><\/p>\n<p><strong>Selecci\u00f3n de adjudicatarios: 07 de agosto de 2020.<\/strong><\/p>\n<p><strong>Notificaci\u00f3n adjudicatarios: 10 de agosto de 2020.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con el fin de apoyar a las mipymes arique\u00f1as ante los desaf\u00edos que han surgido por la pandemia del COVID 19, la Corporaci\u00f3n Municipal de Fomento Productivo Costa Chinchorro, abre llamado a postular a \u201cSistema de pr\u00e9stamos de bicicletas el\u00e9ctricas\u201d con el fin de que los emprendedores arique\u00f1os, que cumplan con los requisitos, puedan postular&hellip;<\/p>\n","protected":false},"author":1,"featured_media":2508,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"post_folder":[],"class_list":["post-2621","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-licitaciones","category-4","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/2621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=2621"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/2621\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/2508"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=2621"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=2621"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=2621"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=2621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}