{"id":3160,"date":"2020-12-03T18:08:40","date_gmt":"2020-12-03T21:08:40","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=3160"},"modified":"2020-12-03T18:08:40","modified_gmt":"2020-12-03T21:08:40","slug":"30-pymes-gastronomicas-son-parte-de-carnaval-de-sabores-en-linea","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/30-pymes-gastronomicas-son-parte-de-carnaval-de-sabores-en-linea\/","title":{"rendered":"30 pymes gastron\u00f3micas son parte de Carnaval de Sabores en l\u00ednea"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Evento se llevar\u00e1 cabo este s\u00e1bado 5 a partir del mediod\u00eda por Facebook live.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Con las recetas de \u00c1lvaro Barrientos y Mikel Zulueta y la presentaci\u00f3n de destacados chefs locales como Fernando Mayorga, Guillermo Castillo y V\u00edctor Quelopana, regresa Carnaval de Sabores en L\u00ednea. La invitaci\u00f3n es para este s\u00e1bado 05 de diciembre a partir de las 12.00 horas v\u00eda Facebook live. En esta oportunidad son cerca de 30 pymes gastron\u00f3micas que se han inscritos con platos a $3.500, la oferta completa la pueden ubicar en CarnavaldeSabores.cl<\/p>\n<p style=\"text-align: justify;\">El objetivo de esta actividad es apoyar las pymes gastron\u00f3micas y productores locales de nuestra ciudad, que se vieron duramente afectadas por la contingencia sanitaria. La iniciativa es organizada por la Corporaci\u00f3n Municipal Costa Chinchorro en conjunto con Inacap Sede Arica y cuenta con el apoyo de los fondos del 6 por ciento del Consejo Regional y del Gobierno Regional de Arica y Parinacota.<\/p>\n<p style=\"text-align: justify;\">Para el presidente del CORE, Claudio Acu\u00f1a Le Blanc, este evento es relevante en cuanto permite apoyar y fortalecer a las pymes afectadas por la pandemia. \u201cLa preocupaci\u00f3n del Consejo Regional ha sido focalizar recursos para que las organizaciones enfrenten la crisis sanitaria y econ\u00f3mica que ha causado esta pandemia, por eso, estamos muy contentos que la Corporaci\u00f3n Municipal Costa Chinchorro haya acogido este llamado y a trav\u00e9s de este peque\u00f1o, pero significativo proyecto, se d\u00e9 un impulso a las micro y peque\u00f1as empresas gastron\u00f3micas afectadas seriamente por los estragos de esta crisis sanitaria. La invitaci\u00f3n es ahora a la comunidad para que participe de este evento\u201d.<\/p>\n<p style=\"text-align: justify;\">El presidente de la Corporaci\u00f3n Municipal Costa Chinchorro, alcalde Gerardo Esp\u00edndola hizo un llamado a los arique\u00f1os y arique\u00f1as a no perderse este evento. \u201cLos quiero invitar para que no se pierdan este s\u00e1bado el Carnaval de Sabores, la fiesta t\u00edpica de la gastronom\u00eda arique\u00f1a, pero que producto de la pandemia la estamos haciendo v\u00eda online. Es un evento para ustedes puedan disfrutar y aprender a hacer alg\u00fan plato de comida con reconocidos chefs locales, nacionales, y por supuesto comprar alg\u00fan plato de comida a nuestros peque\u00f1os empresarios gastron\u00f3micos. No se lo pierdan\u201d.<\/p>\n<p style=\"text-align: justify;\">En tanto, el vicerrector de Inacap, Daniel Uribe, destac\u00f3 la realizaci\u00f3n de esta nueva versi\u00f3n de Carnaval de Sabores en L\u00ednea que permite apoyar a las peque\u00f1as y medianas empresas del rubro gastron\u00f3mico que se han visto afectadas por la pandemia. \u201cEste evento Carnaval de Sabores est\u00e1 en el contexto de nuestros ejes del modelo educativo de INACAP, del compromiso con el desarrollo territorial, del aprendizaje integrado con sectores productivos y de servicios, y en alianza con corporaciones regionales como Costa Chinchorro\u201d.<\/p>\n<p><a class=\"dt-pswp-item\" href=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2020\/12\/CDS_ANIONUEVO_CRONOGRAMA.jpg\" data-dt-img-description=\"\" data-large_image_width=\"1500\" data-large_image_height=\"1500\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-3162\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2020\/12\/CDS_ANIONUEVO_CRONOGRAMA.jpg\" alt=\"\" width=\"1500\" height=\"1500\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento se llevar\u00e1 cabo este s\u00e1bado 5 a partir del mediod\u00eda por Facebook live. Con las recetas de \u00c1lvaro Barrientos y Mikel Zulueta y la presentaci\u00f3n de destacados chefs locales como Fernando Mayorga, Guillermo Castillo y V\u00edctor Quelopana, regresa Carnaval de Sabores en L\u00ednea. La invitaci\u00f3n es para este s\u00e1bado 05 de diciembre a partir&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3161,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-3160","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/3160","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=3160"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/3160\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/3161"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=3160"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=3160"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=3160"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=3160"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}