{"id":3418,"date":"2021-05-27T17:31:24","date_gmt":"2021-05-27T21:31:24","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=3418"},"modified":"2021-05-27T17:31:24","modified_gmt":"2021-05-27T21:31:24","slug":"invitan-a-vivir-la-experiencia-chinchorro-a-traves-de-realidad-aumentada","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/invitan-a-vivir-la-experiencia-chinchorro-a-traves-de-realidad-aumentada\/","title":{"rendered":"Invitan a vivir la experiencia chinchorro a trav\u00e9s de realidad aumentada"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>En el marco de la celebraci\u00f3n del D\u00eda del Patrimonio la CMCC liberar\u00e1 a trav\u00e9s de sus redes un identificador que permitir\u00e1 al usuario acercarse a la Cultura Chinchorro utilizando las nuevas tecnolog\u00edas.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Este fin de semana se celebra en todo Chile el Dia del Patrimonio, es en este marco que la Corporaci\u00f3n Municipal Costa Chinchorro realizar\u00e1 la liberaci\u00f3n de un identificador que permitir\u00e1 a los usuarios que hayan bajado la aplicaci\u00f3n Sariri, descubrir el patrimonio cultural Chinchorro de manera absolutamente distinta, utilizando tecnolog\u00eda de realidad aumentada<\/p>\n<p>Por eso la invitaci\u00f3n es a bajar la aplicaci\u00f3n Sariri a tu celular desde la p\u00e1gina web <a href=\"http:\/\/www.cuevasdeanzota.cl\">www.cuevasdeanzota.cl<\/a>., y que el d\u00eda s\u00e1bado 29 a partir de las 10.00 horas buscar en las redes de la corporaci\u00f3n el identificador e imprimirlo, luego apunta tu celular al identificador y descubre el patrimonio cultural chinchorro como nunca antes lo hab\u00edas visto.<\/p>\n<p>\u201cInvitamos a la comunidad de Arica a que participe de un modo distinto a trav\u00e9s de la tecnolog\u00eda, a trav\u00e9s de la aplicaci\u00f3n que pone a disposici\u00f3n nuestra Corporaci\u00f3n Municipal Costa Chinchorro. Es una actividad distinta para vivirla y disfrutarla en familia\u201d, destac\u00f3 el presidente del directorio de la Corporaci\u00f3n Municipal, el alcalde Gerardo Esp\u00edndola.<\/p>\n<p>Cabe mencionar que este proyecto de realidad aumentada fue realizado durante el 2020 a trav\u00e9s de los Fondos del Ministerio de las Culturas, las Artes y el Patrimonio, y cuyo objetivo principal fue facilitar el acceso de conocimiento al patrimonio arqueol\u00f3gico de la Cultura Chinchorro, a trav\u00e9s del uso de las nuevas tecnolog\u00edas e implementaci\u00f3n de experiencia de realidad aumentada en el Sendero Interpretativo de Cuevas de Anzota, lugar en el que se encuentran dos puntos de realidad aumentada.<\/p>\n<p>\u201cUna manera diferente para conocer la cultura Chinchorro es la que tendremos durante la conmemoraci\u00f3n del D\u00eda del Patrimonio Cultural gracias a esta aplicaci\u00f3n. Una iniciativa innovadora, que a trav\u00e9s de la tecnolog\u00eda nos permite conocer y valorar nuestra herencia patrimonial\u201d, se\u00f1al\u00f3 Hern\u00e1n Zamora, Seremi de las Culturas, las Artes y el Patrimonio.<\/p>\n<p>OTRAS ACTIVIDADES<\/p>\n<p>En este mismo sentido, el d\u00eda viernes 28 de junio la Corporaci\u00f3n Municipal en conjunto con la Oficina de Patrimonio de la Municipalidad de Arica y la Corporaci\u00f3n Chinchorro Marka realizar\u00e1n un taller presentaci\u00f3n de la Cultura Chinchorro y el proyecto de realidad aumentada en tres establecimientos educacionales: Escuela Ricardo Silva Arriagada, Colegio Integrado y Colegio Jhon Wall.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco de la celebraci\u00f3n del D\u00eda del Patrimonio la CMCC liberar\u00e1 a trav\u00e9s de sus redes un identificador que permitir\u00e1 al usuario acercarse a la Cultura Chinchorro utilizando las nuevas tecnolog\u00edas. &nbsp; Este fin de semana se celebra en todo Chile el Dia del Patrimonio, es en este marco que la Corporaci\u00f3n Municipal&hellip;<\/p>\n","protected":false},"author":1,"featured_media":3419,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[5],"post_folder":[],"class_list":["post-3418","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-diadelpatrimonio-chinchorro-arica-sariri","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/3418","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=3418"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/3418\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/3419"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=3418"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=3418"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=3418"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=3418"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}