{"id":4029,"date":"2022-02-16T15:26:02","date_gmt":"2022-02-16T18:26:02","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=4029"},"modified":"2022-02-16T15:26:02","modified_gmt":"2022-02-16T18:26:02","slug":"invitan-a-pymes-gastronomicas-a-sumarse-a-nueva-version-de-carnaval-de-sabores","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/invitan-a-pymes-gastronomicas-a-sumarse-a-nueva-version-de-carnaval-de-sabores\/","title":{"rendered":"Invitan a pymes gastron\u00f3micas a sumarse a nueva versi\u00f3n de Carnaval de Sabores"},"content":{"rendered":"<p>Para la primera semana de abril \u2013 si las condiciones sanitarias lo permiten- est\u00e1 presupuestada una nueva versi\u00f3n de Carnaval de Sabores, iniciativa organizada por la Corporaci\u00f3n Municipal Costa Chinchorro e Inacap, y financiada por el 6 % del FNDR del Gobierno Regional y el Consejo Regional de Arica y Parinacota. En este marco es que los organizadores hicieron un llamado a las pymes gastron\u00f3micas a inscribirse y ser parte de este evento.<\/p>\n<p>El gobernador regional de Arica y Parinacota, Jorge D\u00edaz Ibarra, destac\u00f3 la realizaci\u00f3n de este proyecto, se\u00f1alando que es una buena iniciativa que va a reactivar al mundo gastron\u00f3mico de la regi\u00f3n, que durante la pandemia fue uno de los rubros m\u00e1s afectados. \u201cFueron casi 12 millones de pesos que se destinaron para esta reactivaci\u00f3n econ\u00f3mica. Quiero saludar este proyecto y se\u00f1alar que tambi\u00e9n el recurso regional y del FNDR debe estar destinados a aquellos sectores donde existan oportunidades para que la regi\u00f3n crezca y se desarrolle arm\u00f3nicamente, como en este caso que apoya la reactivaci\u00f3n del rubro de la gastronom\u00eda\u201d.<\/p>\n<p>Por su parte, el presidente de la comisi\u00f3n Social del Consejo Regional, Claudio Acu\u00f1a, manifest\u00f3 su satisfacci\u00f3n por la organizaci\u00f3n de este evento. \u201cUna vez m\u00e1s el Consejo Regional aprueba esta iniciativa que resalta nuestra gastronom\u00eda local, apoyando a las pymes del sector que se han visto afectadas en tiempos de pandemia. Agradecemos a la Corporaci\u00f3n Municipal por impulsar la econom\u00eda local y apoyar a nuestros emprendedores\u201d.<\/p>\n<p>INVITAN A PYMES<\/p>\n<p>Los organizadores de esta actividad hicieron un llamado a las pymes gastron\u00f3micas a inscribirse y ser parte de este evento. \u201cEntendemos que estos \u00faltimos 2 a\u00f1os han sido dif\u00edciles para las pymes locales, es ente marco que junto a Inacap y apoyados por el Gobierno Regional y el Consejo Regional estamos organizando una nueva versi\u00f3n del Carnaval de Sabores. Invitamos a las pymes gastron\u00f3micas a mandarnos sus antecedentes a carnavaldesabores@costachinchorro.cl y participar de este evento que adem\u00e1s nos permite promover nuestra gastronom\u00eda local\u201d, manifest\u00f3 la directora ejecutiva de la Corporaci\u00f3n Municipal Costa Chinchorro, Priscila Aguilera Caimanque.\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4033\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/02\/DSCF0078-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4034\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/02\/DSCF9015-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4035\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/02\/DSCF9177-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4036\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/02\/DSCF9189-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Para la primera semana de abril \u2013 si las condiciones sanitarias lo permiten- est\u00e1 presupuestada una nueva versi\u00f3n de Carnaval de Sabores, iniciativa organizada por la Corporaci\u00f3n Municipal Costa Chinchorro e Inacap, y financiada por el 6 % del FNDR del Gobierno Regional y el Consejo Regional de Arica y Parinacota. En este marco es&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4032,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-4029","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4029","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=4029"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4029\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/4032"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=4029"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=4029"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=4029"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=4029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}