{"id":4683,"date":"2022-08-03T16:12:29","date_gmt":"2022-08-03T20:12:29","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=4683"},"modified":"2022-08-03T16:12:29","modified_gmt":"2022-08-03T20:12:29","slug":"reciclaje-y-construccion-presentan-opcion-ecologica-para-el-desarrollo-comunal","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/reciclaje-y-construccion-presentan-opcion-ecologica-para-el-desarrollo-comunal\/","title":{"rendered":"Reciclaje y construcci\u00f3n: Presentan opci\u00f3n ecol\u00f3gica para el desarrollo comunal"},"content":{"rendered":"<div>\n<p class=\"normal\"><span lang=\"EN\">Baldosas de hormig\u00f3n y pl\u00e1stico reciclado de bidones e insumos de la agricultura de los valles, palmetas de caucho reciclado de neum\u00e1ticos y adoquines que combinan hormig\u00f3n, pl\u00e1stico y vidrio, son algunos de los prototipos de mobiliario p\u00fablico que conoci\u00f3 el alcalde de la Municipalidad de Arica, Gerardo Esp\u00edndola Rojas, acompa\u00f1ado del presidente de la comisi\u00f3n de Medio Ambiente del Concejo Municipal, Daniel Chipana durante su visita en la empresa Innova Green Circular, la cual fue gestionada por la Corporaci\u00f3n Municipal Costa Chinchorro.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Innova Green es una\u00a0 empresa de gesti\u00f3n y valorizaci\u00f3n de residuos, fundada por cuatro empresarios del norte de Chile: Bottai Hermanos, Recauchajes Norte, Transporte Boris Nu\u00f1ez y North Chile Investments, la cual present\u00f3 una alternativa de desarrollo y construcci\u00f3n\u00a0 sustentable a la m\u00e1xima autoridad comunal en tiempos donde se acent\u00faan los efectos del cambio clim\u00e1tico y urge enfrentarlo. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Tras conocer la posibilidades que se abren para el desarrollo de la ciudad con la visita en Innova Green Circular el alcalde de Arica, Gerardo Esp\u00edndola destac\u00f3 la asociatividad local y la vinculaci\u00f3n del mundo empresarial con la comunidad.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u201cAc\u00e1 hay un grupo de empresas que se re\u00fanen para innovar con el elemento de la sostenibilidad ambiental, de poder reciclar, de disminuir la huella de carbono, de pensar en esta econom\u00eda circular e ir revel\u00e1ndose desde el mundo empresarial con el reciclaje y la reutilizaci\u00f3n. Lo interesante ac\u00e1 es que desde nuestra Corporaci\u00f3n Municipal Costa Chinchorro estamos trabajando en esta articulaci\u00f3n con el mundo empresarial, vincul\u00e1ndolo con la sociedad para hacer que esta innovaci\u00f3n que se est\u00e1 produciendo en Arica, se quede ac\u00e1 y poder ver los resultados en nuestros parques, plazas y playas\u201d, coment\u00f3 Esp\u00edndola. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">La Gerente de Innova Green, Claudia Jim\u00e9nez explic\u00f3 que sus productos est\u00e1n certificados porque el laboratorio donde los fabrican lo est\u00e1: \u201ces un proceso industrializado, el trabajo con pl\u00e1stico, vidrio y caucho cumple con las normas necesarias para crear mobiliario urbano como basureros, baldosas, palmetas de caucho, baldosas y adoquines con pl\u00e1stico. Hoy estamos agradecidos de la visita del alcalde de Arica porque en los proyectos de la ciudad se pueden incorporar estos productos\u201d. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">En tanto, el concejal Daniel Chipana, destac\u00f3 el trabajo arique\u00f1o en respeto al ecosistema: \u201ces importante que estas empresas y estos trabajos que se est\u00e1n instalando en nuestra ciudad nos ayuden a mejorar nuestra calidad de vida. Necesitamos empresas que nos puedan ayudar a gestionar este tipo de materiales en beneficio de nuestro mundo, estoy muy contento porque hay personas arique\u00f1as trabajando ac\u00e1 y eso significa que estamos avanzando\u201d.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">PROTOTIPO CON COLILLAS<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Para atender las necesidades de la regi\u00f3n la empresa se propuso crear un prototipo de hormig\u00f3n con colillas de cigarro, pero para ello deb\u00edan contar con seis kilos de materia prima, la cual fue posible recolectar en tres meses por la hoy empresa Arica Playa sin Colillas.\u00a0 <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">La socia fundadora de esta organizaci\u00f3n que realiza educaci\u00f3n ambiental, recolecci\u00f3n y valorizaci\u00f3n de la contaminaci\u00f3n de colillas de cigarro, Alejandra Luna, coment\u00f3 que es \u201cbuen\u00edsimo que el municipio, los servicios p\u00fablicos y las empresas puedan hacerse cargo de este residuo, hoy tenemos una ley que proh\u00edbe arrojar colillas en espacios p\u00fablicos y nos llama a hacernos cargo, pero la fiscalizaci\u00f3n es baja, por tanto es importante tener medios para su recolecci\u00f3n, pero adem\u00e1s es necesario encargarnos de su valorizaci\u00f3n para que no vaya a parar al vertedero, la idea es que esto tengo una soluci\u00f3n y esa soluci\u00f3n se quede en la regi\u00f3n\u201d. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Actualmente solo en la regi\u00f3n de Valpara\u00edso hay una planta que puede reutilizar las colillas de cigarro, pero trasladarlas hasta all\u00e1 significa el pago de impuestos aduaneros y aumentar el impacto de la huella de carbono. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4686\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/08\/reciclaje-y-construccion-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/>\u00a0\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4684\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/08\/reciclaje-y-construccion-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Baldosas de hormig\u00f3n y pl\u00e1stico reciclado de bidones e insumos de la agricultura de los valles, palmetas de caucho reciclado de neum\u00e1ticos y adoquines que combinan hormig\u00f3n, pl\u00e1stico y vidrio, son algunos de los prototipos de mobiliario p\u00fablico que conoci\u00f3 el alcalde de la Municipalidad de Arica, Gerardo Esp\u00edndola Rojas, acompa\u00f1ado del presidente de la&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4685,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[9,18,30],"post_folder":[],"class_list":["post-4683","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-arica-reciclaje-economiacircular","tag-arica","tag-reciclaje","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4683","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=4683"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4683\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/4685"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=4683"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=4683"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=4683"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=4683"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}