{"id":4733,"date":"2022-09-02T13:20:52","date_gmt":"2022-09-02T17:20:52","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=4733"},"modified":"2022-09-02T13:20:52","modified_gmt":"2022-09-02T17:20:52","slug":"vuelve-laucho-bulevar-para-cerrar-el-mes-de-la-infancia","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/vuelve-laucho-bulevar-para-cerrar-el-mes-de-la-infancia\/","title":{"rendered":"Vuelve Laucho Bulevar para cerrar el Mes de la Infancia"},"content":{"rendered":"<div>\n<p class=\"normal\"><span lang=\"EN\">El panorama incluye Cine al aire libre, feria de artesan\u00edas locales, foodtruck y la presentaci\u00f3n del Orfe\u00f3n de Arica en la playa que tiene una renovada imagen.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Con el objetivo de activar playa El Laucho, entregar un espacio de fomento productivo a emprendedores y celebrar en familia el D\u00eda del Ni\u00f1o y la Ni\u00f1a, este fin de semana se realiza una nueva versi\u00f3n de Laucho Bulevar, evento que contar\u00e1 con una feria de artesan\u00edas, delicias gastron\u00f3micas en foodtruck y cine en la arena junto a Arica Nativa. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Este s\u00e1bado 27 y domingo 28 de agosto de 12:00 a 19:00 horas vuelve el panorama familiar de Laucho Bulevar con diferentes sorpresas. Este s\u00e1bado a las 19:00 horas se exhibir\u00e1 la pel\u00edcula del momento: \u201cEncanto\u201d, presentada por Arica Nativa, y el domingo, el Orfe\u00f3n de Arica contagiar\u00e1 su alegr\u00eda invitando a bailar al p\u00fablico con su retreta a partir de las 18:30 horas.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">La directora ejecutiva de Costa Chinchorro, Daniela Ortega Lau, explic\u00f3 que la actividad busca generar una vitrina para que las y los emprendedores de la regi\u00f3n puedan mostrar su trabajo, el cual tiene un foco en la identidad regional en uno de los espacios administrados por nuestra Corporaci\u00f3n como lo es playa El Laucho.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u201cBuscamos generar un espacio atractivo para el emprendimiento y para ofrecer a los visitantes y comunidad. La idea es poner en valor el borde costero sur, entregar un panorama distinto para las familias arique\u00f1as y apoyar a nuestros emprendedores y emprendedoras que lo han pasado bastante mal. Invitamos a la comunidad a disfrutar de una tarde entretenida en la playa junto a su familia, y que no olviden\u00a0 traer su manta para ver la pel\u00edcula en la arena y disfrutar de la experiencia tur\u00edstico-gastron\u00f3mica que tendremos para cerrar el Mes de la Infancia\u201d.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><strong><span lang=\"EN\">ARTESAN\u00cdAS CON IDENTIDAD REGIONAL<\/span><\/strong><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">En alianza con la Asociaci\u00f3n de Emprendedores de Chile, Asech, se impulsan ferias de fomento productivo para activar el borde costero sur a trav\u00e9s de la puesta en valor de artesan\u00edas con identidad cultural. De esta manera se podr\u00e1n conocer cuellos y abrigos con tela de aguayo, caminos de mesa con bordados de fauna local, jabones y cremas artesanales con productos agr\u00edcolas, fotograf\u00edas de aves del Humedal del r\u00edo Lluta, aceites nutritivos para el cabello, recuerdos con identidad ind\u00edgena y muchos otros productos elaborados a mano.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Para la realizaci\u00f3n de estos espacios\u00a0 se adquirieron toldos, mesas y sillas que son usados en activaciones como Carnaval de Sabores, Laucho Bulevar, Isla Bulevar y cada vez que hay actividades deportivas en el borde costero con el calendario <\/span><span lang=\"EN\">\u201cArica Siempre Activa, Capital del Deporte\u201d, impulsado por Corfo a trav\u00e9s del Programa Estrat\u00e9gico Regional. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Esta inversi\u00f3n de m\u00e1s de tres millones de pesos fue realizada con parte del fondo basal que recibi\u00f3 Costa Chinchorro en el primer semestre desde la Municipalidad de Arica. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Loreto Garc\u00eda Rodr\u00edguez, dise\u00f1adora de vestuario y due\u00f1a de \u201cEl Rebelde Custom Jacket\u201d, coment\u00f3 que se trata de una instancia valorable: \u201cadem\u00e1s de estar en un paisaje privilegiado, es un buen momento para conocernos entre emprendedores y para poder darle una inyecci\u00f3n a estos tiempos que han sido dif\u00edciles para todos los que emprendemos y trabajamos de las artes o artesan\u00edas\u201d. <\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Priscila Rodriguez de \u201cAmatista Bazar\u201d, destac\u00f3 lo c\u00f3modo que resulta llegar e instalarse: \u201ctienen toldos, mesas y sillas, y nosotros solo llegamos con las ganas de trabajar: Ojal\u00e1 se siga impulsando y ser\u00eda bueno que para el verano se abra nuevamente el espacio. Me gusta\u201d. Militza Riquelme, de Kusi Arica, agreg\u00f3 estar agradecida de exponer sus trabajos, \u201cesta feria es importante para el turismo, nosotros traemos creaciones hechas a mano y el patrimonio que tenemos en Arica y eso es beneficioso tanto para el turista como para el arique\u00f1o\u201d.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">Playa El Laucho se encuentra en administraci\u00f3n de la Corporaci\u00f3n Municipal Costa Chinchorro y est\u00e1 habilitada todo el a\u00f1o con servicios higi\u00e9nicos, salvavidas, enfermer\u00eda y otros. En esta oportunidad la corporaci\u00f3n presenta una nueva imagen de las letras monumentales, las cuales fueron reparadas y lucen una nueva imagen con un dise\u00f1o basado en la l\u00ednea gr\u00e1fica del Programa de Revitalizaci\u00f3n de Barrios e Infraestructura Patrimonial Emblem\u00e1tica(PRBIPE) que se encuentra en el centro de la ciudad.<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u00a0<\/span><\/p>\n<\/div>\n<div>\n<p class=\"normal\"><span lang=\"EN\">\u201cHemos invertido en mejorar su imagen para que la comunidad visite y aproveche este recinto, no s\u00f3lo en materia de generar espacios para compartir en familia , sino adem\u00e1s en fortalecer la seguridad, implementar la sala de primeros auxilios,\u00a0 el mejoramiento bombas ba\u00f1os, entre otras inversiones,, la idea es que la gente se acerque y ocup\u00e9 positivamente su borde costero\u201d, finaliz\u00f3 la directora ejecutiva de Costa Chinchorro.<\/span><\/p>\n<\/div>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-4736 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/09\/Artesanos-Laucho-bulevard-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El panorama incluye Cine al aire libre, feria de artesan\u00edas locales, foodtruck y la presentaci\u00f3n del Orfe\u00f3n de Arica en la playa que tiene una renovada imagen. \u00a0 Con el objetivo de activar playa El Laucho, entregar un espacio de fomento productivo a emprendedores y celebrar en familia el D\u00eda del Ni\u00f1o y la Ni\u00f1a,&hellip;<\/p>\n","protected":false},"author":1,"featured_media":4735,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[18,44,45,46],"post_folder":[],"class_list":["post-4733","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-arica","tag-emprendedores","tag-laucho-bulevar","tag-playa-el-laucho","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=4733"}],"version-history":[{"count":0,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4733\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/4735"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=4733"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=4733"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=4733"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=4733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}