{"id":4803,"date":"2022-09-23T12:07:27","date_gmt":"2022-09-23T15:07:27","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=4803"},"modified":"2023-04-28T17:20:02","modified_gmt":"2023-04-28T21:20:02","slug":"con-nuevas-reglas-de-acceso-y-reduccion-de-aforo-vuelve-atencion-de-publico-en-cuevas-de-anzota","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/con-nuevas-reglas-de-acceso-y-reduccion-de-aforo-vuelve-atencion-de-publico-en-cuevas-de-anzota\/","title":{"rendered":"Con nuevas reglas de acceso y reducci\u00f3n de aforo vuelve atenci\u00f3n de p\u00fablico en Cuevas de Anzota"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-4804 size-full\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2022\/09\/Anzota-1.jpeg\" alt=\"El sendero cuenta con se\u00f1al\u00e9tica que demarca las zonas de riesgo\" width=\"1024\" height=\"682\" \/><\/p>\n<p>Tras dos meses cerradas, la atenci\u00f3n al p\u00fablico en Cuevas de Anzota vuelve a partir del 16 de septiembre en su horario de verano, desde las 9 de la ma\u00f1ana hasta las 19 horas. Esta decisi\u00f3n fue tomada por la Corporaci\u00f3n Municipal Costa Chinchorro, tras una serie de medidas para asegurar la protecci\u00f3n de los visitantes y prevenir accidentes en uno de los sitios m\u00e1s tur\u00edsticos de Arica, con un promedio de 120 mil ingresos al a\u00f1o.<\/p>\n<p>&nbsp;<\/p>\n<p>Estas medidas tienen relaci\u00f3n con las obras de reparaci\u00f3n de barandas y cuerdas, adem\u00e1s de la limpieza del sendero tras un importante derrumbe ocurrido el 28 de junio debido a un sismo de menor intensidad. Una vez entregada la obra, junto a un experto en prevenci\u00f3n de riesgos se identificaron y marcaron las \u00e1reas m\u00e1s peligrosas para el tr\u00e1nsito de personas, para as\u00ed evitar fotograf\u00edas o pausas en dichas partes del sendero. Paralelo a ello, la corporaci\u00f3n elabor\u00f3 un plan de Seguridad y Respuesta ante contingencias, el que se podr\u00eda poner en marcha en cualquier momento desde su apertura.<\/p>\n<p>&nbsp;<\/p>\n<p>La directora ejecutiva de la Corporaci\u00f3n Costa Chinchorro, Daniela Ortega Lau, explic\u00f3 que las nuevas medidas buscan ofrecer mayor seguridad a los visitantes en un paseo insigne de la ciudad, pero que requiere ciertos cuidados \u201cEstamos abriendo las Cuevas de Anzota con una serie de medidas tomadas tras el cierre que ocasion\u00f3 el sismo de 4.9 grados y produjo una gran destrucci\u00f3n en el sector Am\u00e9rica del Sur del sendero. En estos meses reparamos el lugar, se contrat\u00f3 un plan de seguridad con un experto en prevenci\u00f3n de riesgo y demarcamos zonas en las que las personas no deben detenerse. Este es un sector de una belleza \u00fanica, pero que requiere del autocuidado de quienes nos visitan\u201d. Ortega adelant\u00f3 que se est\u00e1 trabajando adem\u00e1s en estudios del macizo, con la Direcci\u00f3n de obras portuarias, entre otras acciones mayores y a largo plazo.<\/p>\n<p>&nbsp;<\/p>\n<p>Las nuevas medidas de prevenci\u00f3n incluyen evitar el uso de calzado abierto por el desprendimiento de piedras; sugieren que el ingreso sea a partir de los 3 a\u00f1os de edad, pues no existen cascos para los m\u00e1s peque\u00f1os y reducen al aforo a 80 personas. Estas fueron presentadas a un grupo de operadores tur\u00edsticos, con el fin de conocer las normativas. Santa Chog\u00f1a, de Turismo Chog\u00f1a; Carolina Cort\u00e9z de Turismo Lauca; Franco Rojas, coordinador del programa Arica Siempre Activa y Jessica Rosas, presidenta de la Agrupaci\u00f3n de Gu\u00edas de Turismo de Arica y Parinacota, adem\u00e1s del concejal Max Schauer, recorrieron el sendero y entregaron sugerencias para implementar a futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>Por otra parte, el presidente de la Corporaci\u00f3n y alcalde Gerardo Esp\u00edndola valor\u00f3 la apertura de las Cuevas de Anzota y realiz\u00f3 un llamado a seguir las medidas de protecci\u00f3n. \u201cLuego de un periodo de conservaci\u00f3n y de contratar a un prevencionista de riesgos, estamos tomando acciones que van en resguardo de la poblaci\u00f3n. Nos alegramos de la apertura del sendero y llamamos a la comunidad a visitarlas con todas las medidas de protecci\u00f3n y a visitar la p\u00e1gina <a href=\"http:\/\/www.costachinchorro\">www.costachinchorro<\/a>.cl para conocer la nueva informaci\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras dos meses cerradas, la atenci\u00f3n al p\u00fablico en Cuevas de Anzota vuelve a partir del 16 de septiembre en su horario de verano, desde las 9 de la ma\u00f1ana hasta las 19 horas. Esta decisi\u00f3n fue tomada por la Corporaci\u00f3n Municipal Costa Chinchorro, tras una serie de medidas para asegurar la protecci\u00f3n de los&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-4803","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4803","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=4803"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4803\/revisions"}],"predecessor-version":[{"id":5689,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/4803\/revisions\/5689"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/5468"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=4803"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=4803"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=4803"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=4803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}