{"id":5164,"date":"2023-02-09T17:10:54","date_gmt":"2023-02-09T20:10:54","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=5164"},"modified":"2023-04-24T21:34:36","modified_gmt":"2023-04-25T01:34:36","slug":"nustas-tuvieron-previa-del-carnaval-en-lounge-by-rayu","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/nustas-tuvieron-previa-del-carnaval-en-lounge-by-rayu\/","title":{"rendered":"\u00d1ustas tuvieron previa del Carnaval en Lounge by Ray\u00fa"},"content":{"rendered":"<p>Danzas de morenada, caporal, pueblos y diablada compartieron la pista<\/p>\n<p>Con todo el glamour y buen ambiente que entrega Lounge by Ray\u00fa, \u00f1ustas e inkas del Carnaval Andino con la Fuerza del Sol disfrutar una noche de entretenci\u00f3n antes del gran evento tur\u00edstico que estuvo pausado durante dos a\u00f1os.<\/p>\n<p>Un total de 13 agrupaciones fueron representadas en la Presentaci\u00f3n de \u00d1ustas e Inkas que realiz\u00f3 el restobar Lounge by Ray\u00fa en colaboraci\u00f3n con Corporaci\u00f3n Municipal Costa Chinchorro.<\/p>\n<p>Marcelo Fuentelzar, administrador de Lounge by Ray\u00fa coment\u00f3 que durante los casi ocho a\u00f1os del restobar, siempre han estado comprometidos con el turismo y por ello son parte de los auspiciadores: \u201cpara nosotros es importante mostrar Arica, no s\u00f3lo lo que ocurre durante el d\u00eda sino tambi\u00e9n lo que ocurre durante la noche, con uno de los principales polos de atenci\u00f3n como es Lounge by Ray\u00fa. Luego de dos a\u00f1os estando lejos del Carnaval, nuestro p\u00fablico extra\u00f1aba esto, as\u00ed que nos hicimos parte de este hermoso sentimiento, como<br \/>\nauspiciadores y con la presentaci\u00f3n de las \u00f1ustas\u201d.<\/p>\n<p>Durante la jornada se presentaron \u00f1ustas e inkas de Morenadas Residentes Bolivianos, Achachis Generaci\u00f3n 90, y F\u00e1naticos 8 de diciembre; desde caporales estuvieron Sangre Andina, San Gabriel, Or\u00edgenes San Andr\u00e9s; Diablada Wari Quwac; y desde los pueblos del<br \/>\nnorte Chapiqui\u00f1a, Pachama y Copaquilla, Hijos de Chiapa, Hijos de Caquena, Hijos de Saxamar, Hijos de Guallatire, y la Orquesta de Putre.<\/p>\n<p>Carolina S\u00e1nchez Alcayaga, \u00f1usta de la majestuosa diablada Wari Quwac, explic\u00f3 la importancia de lo que significa ser \u00f1usta en el Carnaval Andino con la Fuerza del Sol, al representar a los bailarines y mostrar a todo Chile y el mundo las danzas de esta macrozona andina.<\/p>\n<p>\u201cEs un honor ser \u00f1usta porque es a trav\u00e9s de una votaci\u00f3n a mano alzada de los bailarines. Este a\u00f1o es bastante especial donde Chile y el mundo estuvo encerrada por miedo y con bastantes limitaciones. Ahora nosotros podemos representar nuestro arte a todo el mundo y<br \/>\nlo hacemos con mucho entusiasmo, mucha energ\u00eda y mucha pasi\u00f3n por lo que nosotros<br \/>\nhacemos como bailarines\u201d.<\/p>\n<p>Mikaela Mamani, \u00f1usta de Hijos de Chiapa coment\u00f3 que ser \u00f1usta en su agrupaci\u00f3n significa representar a todo un pueblo e incluso una quebrada, espec\u00edficamente la de Aroma: \u201cbailamos y celebramos por ellos y cantamos sus cantos\u201d. El inka de Hijos de Chiapa, N\u00e9stor Vargas, agreg\u00f3 que ellos representan a los bailarines quienes son los protagonistas del Carnaval: \u201cellos son quienes est\u00e1n siempre acompa\u00f1ando a la agrupaci\u00f3n y quienes nos entregan todo en el Carnaval, uno se siente acompa\u00f1ado por ellos porque entregan todo su cari\u00f1o para poder participar\u201d.<\/p>\n<p>Este viernes 3, s\u00e1bado 4 y domingo 5 de febrero se vivir\u00e1 el Carnaval Andino con la Fuerza del Sol con 68 comparsas desde el mediod\u00eda hasta las seis de la ma\u00f1ana en el centro de Arica.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5168\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/02\/previa-nustas-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5169\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/02\/nustas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5167\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/02\/nustas-5-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5166\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/02\/nustas-4-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5165 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/02\/inkas-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Danzas de morenada, caporal, pueblos y diablada compartieron la pista Con todo el glamour y buen ambiente que entrega Lounge by Ray\u00fa, \u00f1ustas e inkas del Carnaval Andino con la Fuerza del Sol disfrutar una noche de entretenci\u00f3n antes del gran evento tur\u00edstico que estuvo pausado durante dos a\u00f1os. Un total de 13 agrupaciones fueron&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5169,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-5164","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5164","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=5164"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5164\/revisions"}],"predecessor-version":[{"id":5330,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5164\/revisions\/5330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/5169"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=5164"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=5164"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=5164"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=5164"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}