{"id":5240,"date":"2023-03-13T13:05:30","date_gmt":"2023-03-13T16:05:30","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=5240"},"modified":"2023-04-24T21:34:36","modified_gmt":"2023-04-25T01:34:36","slug":"refuerzan-seguridad-en-anzota-tras-inusual-mortandad-de-lobos-marinos","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/refuerzan-seguridad-en-anzota-tras-inusual-mortandad-de-lobos-marinos\/","title":{"rendered":"Refuerzan seguridad en Anzota tras inusual mortandad de lobos marinos"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Se solicitaron recursos para disposici\u00f3n final de animales de gran tama\u00f1o y labores de aseo.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Tras el aumento inusual de mortalidad de lobos marinos, el presidente de la Corporaci\u00f3n Municipal Costa Chinchorro, alcalde Gerardo Esp\u00edndola Rojas, solicit\u00f3\u00a0 una mesa intersectorial para coordinar acciones de retiro y aseo.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">En la reuni\u00f3n que cont\u00f3 con la participaci\u00f3n del delegado presidencial, seremi de gobierno, Senapred, Sag y Sernapesca, se defini\u00f3 solicitar recursos a nivel central para disposici\u00f3n final y retiro de los animales de gran tama\u00f1o. Si bien a\u00fan no se sabe la raz\u00f3n de la mortandad, se realizan muestras por gripe aviar, tras hallazgo positivo de un chungungo en el Humedal del r\u00edo Lluta y otros casos de lobos marinos en Antofagasta.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Gerardo Esp\u00edndola manifest\u00f3 que la Municipalidad est\u00e1 haciendo el retiro de todas las aves y lobos marinos en gran parte del litoral, pero esto mejorar\u00e1 tras las coordinaciones realizadas.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cAhora viene un apoyo externo para esta emergencia sanitaria que se est\u00e1 viviendo, para que adem\u00e1s del Municipio podamos tener otros dispositivos y otros servicios que puedan llegar incluso a sectores mucho m\u00e1s alejados como La Liserilla que est\u00e1 pasado las Cuevas de Anzota\u201d.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Frente al posible avance de este virus que pueda afectar la econom\u00eda nacional, se evalu\u00f3 mantener abierto el sendero de Cuevas de Anzota, siguiendo las indicaciones del SAG y llamando a informar sobre hallazgos de animales muertos sin manipularlos<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">\u201cLo que se est\u00e1 viviendo hoy en Latinoam\u00e9rica, especialmente en las costas producto de la gripe aviar, es el impacto que puede pasar en la econom\u00eda como en Argentina que se han visto afectadas las aves de consumo. Estamos atendiendo todos los requerimientos que nos indica el SAG como lo es tener un pediluvio, limpiar los cascos y el llamado a la gente que visita estos lugares es que si ven un lobo o una ave que est\u00e1 muerta, no tomarla y nos pueda dar aviso para que podamos hacer el retiro del lugar\u201d, coment\u00f3 el presidente de la Corporaci\u00f3n.\u00a0<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">El delegado presidencial Ricardo Sanzana, manifest\u00f3 que se est\u00e1n tomando medidas porque ya se ha llegado a la mortandad del 10% de los lobos marinos de la regi\u00f3n: \u201cSag, Sernapesca, Cenapred y nosotros como gobierno junto a la Municipalidad est\u00e1n trabajando para efectos del retiro r\u00e1pido y al disposici\u00f3n final. Estamos en proceso de verificar el personal que se necesita y los medios para hacer una disposici\u00f3n final de cad\u00e1veres de animales de gran dimensi\u00f3n como son los lobos marinos\u201d<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-weight: 400;\">Es as\u00ed como se mantiene el funcionamiento normal del sendero de Cuevas de Anzota de martes a domingo de 9 a 19 horas, con aforo de 80 personas, quienes deben ingresar con zapato cerrado, usar el casco que entrega la corporaci\u00f3n y no acercarse a animales.\u00a0<\/span><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-5241 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/web\/wp-content\/uploads\/2023\/03\/mesa-intersectorial-gripe-aviar-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-5242 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/03\/pediluvio-anzota-2-225x300.jpeg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/03\/pediluvio-anzota-2-225x300.jpeg 225w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/03\/pediluvio-anzota-2-768x1024.jpeg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/03\/pediluvio-anzota-2-1152x1536.jpeg 1152w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/03\/pediluvio-anzota-2.jpeg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se solicitaron recursos para disposici\u00f3n final de animales de gran tama\u00f1o y labores de aseo. &nbsp; Tras el aumento inusual de mortalidad de lobos marinos, el presidente de la Corporaci\u00f3n Municipal Costa Chinchorro, alcalde Gerardo Esp\u00edndola Rojas, solicit\u00f3\u00a0 una mesa intersectorial para coordinar acciones de retiro y aseo.\u00a0 &nbsp; En la reuni\u00f3n que cont\u00f3 con&hellip;<\/p>\n","protected":false},"author":1,"featured_media":5242,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"post_folder":[],"class_list":["post-5240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=5240"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5240\/revisions"}],"predecessor-version":[{"id":5325,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/5240\/revisions\/5325"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/5242"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=5240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=5240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=5240"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=5240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}