{"id":6273,"date":"2023-11-16T12:28:22","date_gmt":"2023-11-16T15:28:22","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=6273"},"modified":"2023-11-16T12:28:22","modified_gmt":"2023-11-16T15:28:22","slug":"corporacion-costa-chinchorro-rindio-cuentas-en-asamblea-de-socios","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/corporacion-costa-chinchorro-rindio-cuentas-en-asamblea-de-socios\/","title":{"rendered":"Corporaci\u00f3n Costa Chinchorro rindi\u00f3 cuentas en asamblea de socios"},"content":{"rendered":"<p dir=\"ltr\">La ejecuci\u00f3n anual en 2022 y 2023 duplic\u00f3 la subvenci\u00f3n municipal.<\/p>\n<p dir=\"ltr\">Como parte de sus estatutos y su gesti\u00f3n por la transparencia, la<a href=\"https:\/\/www.facebook.com\/costachinchorro?__cft__[0]=AZWUR0mkS84O0f1QzOulFgutLZNem8DSQc_G1N1RZ3zUTz3jnTSJhtvNr_9WYA-yr4RhbhTMwXLiu8soYtqRsU88-PnLjv8Gs7RKfmoZLc8s6jZzRKMG4PW3Jd2LeCHYXlWm_p7r57ZkGrU60kBqkVAOdoiQEn61DxEJFBuieJ-aUS06yi_sZJKdhNNpzj8JRXU&amp;__tn__=-]K-R\" target=\"_blank\" rel=\"noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.facebook.com\/costachinchorro?__cft__%5B0%5D%3DAZWUR0mkS84O0f1QzOulFgutLZNem8DSQc_G1N1RZ3zUTz3jnTSJhtvNr_9WYA-yr4RhbhTMwXLiu8soYtqRsU88-PnLjv8Gs7RKfmoZLc8s6jZzRKMG4PW3Jd2LeCHYXlWm_p7r57ZkGrU60kBqkVAOdoiQEn61DxEJFBuieJ-aUS06yi_sZJKdhNNpzj8JRXU%26__tn__%3D-%5DK-R&amp;source=gmail&amp;ust=1700230493003000&amp;usg=AOvVaw2qzbSjN08tIVI0vgPZpbfd\">\u00a0<\/a>Corporaci\u00f3n Municipal Costa Chinchorro\u00a0realiz\u00f3 la asamblea de socios donde present\u00f3 el balance y rendici\u00f3n de cuentas de la gesti\u00f3n 2022 y 2023. En la ocasi\u00f3n, se modificaron estatutos respecto a la cuota de incorporaci\u00f3n y se fij\u00f3 la pr\u00f3xima asamblea para coordinar el comit\u00e9 electoral para elegir nuevo directorio.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">En la reuni\u00f3n se present\u00f3 la memoria 2022 y se presentaron los resultados de la gesti\u00f3n 2022 y 2023 con n\u00fameros, duplicando los recursos otorgados por la subvenci\u00f3n municipal anual. Durante 2022 se gestionaron $1.300 millones y se recibi\u00f3 una subvenci\u00f3n de $689 millones, mientras que en lo que va del 2023 se han ejecutado $1.655.733 millones en proyectos, sobre la base de una subvenci\u00f3n municipal de $770 millones.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">El presidente del directorio, el alcalde Gerardo Esp\u00edndola Rojas destac\u00f3 la gesti\u00f3n de la corporaci\u00f3n y su capacidad para generar confianza en el mundo privado y p\u00fablico.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">\u201cFue una buena asamblea de socios, pudimos mostrar la madurez que ha tenido nuestra corporaci\u00f3n de modo silencioso, especialmente en la administraci\u00f3n de sitios, en la econom\u00eda circular, las nuevas econom\u00edas e industrias y otras \u00e1reas que se est\u00e1n levantando. Es interesante ver como personas del mundo privado y del mundo p\u00fablico se re\u00fanen y conf\u00edan en esta corporaci\u00f3n. Nos estamos transformando en un buen agente de gesti\u00f3n y un actor de innovaci\u00f3n y emprendimiento en la ciudad\u201d.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">Estuvieron presentes el presidente del directorio, Gerardo Esp\u00edndola Rojas; el director municipal Gonzalo Ramos; y los socios Julio Silva de Ubiavis; Miguel Maldonado presidente de la C\u00e1mara de Turismo y empresario de Hotel Spa Las Taguas; Cristian Leiva, director y empresario en Hotel Plaza Colon; Jorge C\u00e1ceres gerente de Empresa Portuaria Arica; Sergio Draguicevic de Chilex; y Daniel Uribe, vicerrector Inacap Sede Arica.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">TRABAJO DESTACADO<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">El gerente de Puerto Arica, Jorge C\u00e1ceres, coment\u00f3 que la Corporaci\u00f3n se ha transformado en una unidad ejecutora \u201cimportante\u201d en Arica, \u201cgenerando una cartera de proyectos y programas, y al mismo tiempo administrando profesionalmente nuestro borde costero que es nuestro principal atractivo como ciudad\u201d.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\">Por su parte, Julio Silva de Ubiavis agradeci\u00f3 el trabajo desarrollando por la Corporaci\u00f3n Costa Chinchorro: \u201clo m\u00e1s importante es que ya est\u00e1n apalancando recursos que vienen de afuera, hay instituciones como el Gobierno Regional que ha aportado varios millones de pesos\u00a0 y esto ha bajado el peso de la Municipalidad para hacer el aporte. La corporaci\u00f3n ya est\u00e1 consolidada, tiene su marca y prestigio, lo que ha sido importante para Arica\u201d.<\/p>\n<p dir=\"ltr\">Finalmente, el empresario tur\u00edstico Sergio Draguisevic coment\u00f3 estar sorprendido por el trabajo de la Corporaci\u00f3n: \u201clos n\u00fameros hablan muy bien de la gesti\u00f3n que han realizado, se ha mantenido como un ente importante de la ciudad con varias actividades, sum\u00e1ndose a varios de los eventos importantes, as\u00ed que agradecido, sorprendido y tratando de sumar m\u00e1s gente a ser parte de la Corporaci\u00f3n\u201d.<\/p>\n<p dir=\"ltr\">\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6276 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-socios-2023-1-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6275 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-3-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n<p dir=\"ltr\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-6274 aligncenter\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2023\/11\/asamblea-de-socios-2023-2-2048x1365.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ejecuci\u00f3n anual en 2022 y 2023 duplic\u00f3 la subvenci\u00f3n municipal. Como parte de sus estatutos y su gesti\u00f3n por la transparencia, la\u00a0Corporaci\u00f3n Municipal Costa Chinchorro\u00a0realiz\u00f3 la asamblea de socios donde present\u00f3 el balance y rendici\u00f3n de cuentas de la gesti\u00f3n 2022 y 2023. En la ocasi\u00f3n, se modificaron estatutos respecto a la cuota de&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6276,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"post_folder":[],"class_list":["post-6273","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-54","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6273","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=6273"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6273\/revisions"}],"predecessor-version":[{"id":6277,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6273\/revisions\/6277"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/6276"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=6273"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=6273"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=6273"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=6273"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}