{"id":6318,"date":"2024-01-22T15:08:07","date_gmt":"2024-01-22T18:08:07","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=6318"},"modified":"2024-01-22T15:08:07","modified_gmt":"2024-01-22T18:08:07","slug":"carnaval-de-arica-recibe-100-millones-en-auspicios-este-2024","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/carnaval-de-arica-recibe-100-millones-en-auspicios-este-2024\/","title":{"rendered":"Carnaval de Arica recibe 100 millones en auspicios este 2024"},"content":{"rendered":"<p>A trav\u00e9s de la gesti\u00f3n de Corporaci\u00f3n Municipal Costa Chinchorro, el Carnaval Andino con la Fuerza del Sol consigui\u00f3 el aporte de empresas,<br \/>\npymes y emprendedores que asciende a 100 millones de pesos, con lo cual se mejorar\u00e1 la seguridad, difusi\u00f3n y producci\u00f3n.<\/p>\n<p>Un total de 41 empresas de alcance local, regional y nacional apoyan el mayor evento cultural del norte de Chile. Sus aportes se traducen en la incorporaci\u00f3n de 60 guardias en todo el circuito de 20:00 a 08:00 horas; dos ambulancias; ornamentaci\u00f3n del recorrido y escenarios; avisos publicitarios de Iquique a Coquimbo; producci\u00f3n de viajes y eventos de difusi\u00f3n con la participaci\u00f3n de \u00f1ustas; invitaci\u00f3n de canales de televisi\u00f3n nacional (CNN y Canal 13); y 4.000 art\u00edculos publicitarios como lo son gorros, abanicos, pa\u00f1uelos, totebag, quitasoles, entre otros.<\/p>\n<p>El presidente del directorio de la Corporaci\u00f3n Municipal Costa Chinchorro, el alcalde Gerardo Esp\u00edndola Rojas, destac\u00f3 el aporte del sector privado para hacer el Carnaval m\u00e1s seguro, relevando que este evento le pertenece a toda la comunidad.<\/p>\n<p>\u201cLevantar el Carnaval es una tarea tit\u00e1nica que la encabeza bailarines en sus diferentes agrupaciones, el estado a trav\u00e9s de la Municipalidad y hace tres a\u00f1os a trav\u00e9s del trabajo que realiza nuestra Corporaci\u00f3n Municipal Costa Chinchorro podemos recibir auspicios que nos permiten levantar muchas cosas, desde las gr\u00e1ficas, impresiones, publicidad, la gesti\u00f3n de residuos, la contrataci\u00f3n de guardias que le dar\u00e1 mucha m\u00e1s seguridad a bailarines en especial en la noche porque ac\u00e1 se baila desde el atardecer al alba. Tenemos como auspiciadores grandes empresas y pymes, porque entendemos que este Carnaval le pertenece a Arica y la ciudad la hacemos entre todas y todos\u201d.<\/p>\n<p>Por su parte la directora ejecutiva de Costa Chinchorro, Daniela Ortega Lau, destac\u00f3 el esfuerzo del equipo de funcionarios por alcanzar la cifra que dobla los auspicios del 2023<\/p>\n<p>\u201cA trav\u00e9s de la mesa Carnaval asumimos la labor de sumar a los privados al desarrollo del Carnaval, con aportes que sirven para que el Carnaval sea mucho mejor, tendremos guardias de seguridad, difusi\u00f3n, canales de televisi\u00f3n nacional, difusi\u00f3n hasta la cuarta regi\u00f3n a trav\u00e9s de Madero, es decir llegar a m\u00e1s turistas. Quiero destacar al equipo, dise\u00f1adores, fomento productivo, finanzas, todos nos hemos abocado al Carnaval y hemos logrado doblar los aportes del a\u00f1o pasado\u201d<\/p>\n<p>Por segundo a\u00f1o consecutivo se ha sumado el auspicio de pymes locales, demostrando que el carnaval es de todas y todos los arique\u00f1os. Estos aportes son en dinero, alcanzando los $57 millones, y tambi\u00e9n en canjes o aportes no pecuniarios que sobrepasan los $43 millones.<\/p>\n<p>Marcela Cerda S\u00e1nchez, subgerenta de Mallplaza Arica coment\u00f3 que para su empresa son importantes las personas que habitan el territorio y ante la motivaci\u00f3n de las y los arique\u00f1os por la cultura, prepar\u00e1ndose todo un a\u00f1o para el Carnaval, es muy importante participar: \u201cEs muy importante para nosotros ser part\u00edcipes de esta gran fiesta multicultural que no solo envuelve a la regi\u00f3n de Arica y Parinacota, sino que tambi\u00e9n a todo el pa\u00eds y tambi\u00e9n a Latinoam\u00e9rica\u201d.<\/p>\n<p>Richard Hern\u00e1ndez Palape, due\u00f1o de ferreter\u00eda Rivamac, agreg\u00f3 que ser auspiciador del carnaval es muy importante para las pymes, \u201cporque nos da una ventanita para poder mostrarnos y tambi\u00e9n apoyar una iniciativa muy importante para Arica y para el mundo\u201d.<\/p>\n<p>Otra pyme que mostr\u00f3 su alegr\u00eda de participar fue Divertikids, a trav\u00e9s de su due\u00f1o Francisco Hern\u00e1ndez, quien coment\u00f3 que es un \u201chonor ser parte de este gran evento cultural, nuestras hijas participan bailando, con esfuerzo estamos participando para todos<br \/>\nustedes\u201d.<\/p>\n<p>Todo este aporte privado se suma a la producci\u00f3n que realiza la Municipalidad de Arica que asciende a m\u00e1s de $1.000 millones en producci\u00f3n y premiaci\u00f3n de las agrupaciones. Asimismo, est\u00e1 el aporte personal de cada uno de los y las bailarines quienes invierten en vestuario, bandas musicales, accesorios, maquillaje, peinados, seguimiento fotogr\u00e1fico, entre otros.<\/p>\n<p>UNIDAD<br \/>\nMart\u00edn Montecinos presidente de la Confraternidad de Bailes Andinos destac\u00f3 el sentido de unidad de este Carnaval siendo \u00fanico por destacar danzas m\u00e1s all\u00e1 de las actuales fronteras.<\/p>\n<p>\u201cEstamos muy felices de que nos estemos uniendo en el Carnaval m\u00e1s lindo y grande de Chile, el \u00fanico carnaval de Latinoam\u00e9rica que une a tres pa\u00edses que son Chile, Per\u00fa y Bolivia, las danzas son internacionales y lo reconocemos, estas se juntan con las danzas de nuestros pueblos como Putre, Socoroma, Saxamar, Codpa, Chapiqui\u00f1a, en fin todos nuestros pueblos de precordillera y cordillera m\u00e1s el pueblo tribal afrodescendiente\u201d.<\/p>\n<p>Luego de un pasacalle liderado por el Orfe\u00f3n de Arica junto a \u00f1ustas de las comparsas participantes se dio a conocer desde Mallplaza Arica los nombres de los 41 auspiciadores del Carnaval, que son Coca- Cola, Mallplaza, TPA, Zofri, Condensa, L\u00edquidos Kukuli, EPA, Ambipar-Recinor, Aguas del Altiplano, Madero, Antay, Repuestos Acira, Cargo Arica, Agr\u00edcola del Norte, Arica es bacan, Imprenort, Diverti Kids,RQB Constructora, Colegio de Periodoncistas, Universidad Santo Tomas, Onlyone, Caeli, Rivamac, Kenner, Anata Gourmet, Hotel Arica, Empanadas Lico Lico, Nuke, Caimanque Eco Food, Steel North, Taxi Kata, Farmacias Isa\u00edas, Farmacias Urgencias, Sunset, Silkscreen, Aurus, Elsaborcito,<br \/>\nAgencia publicitaria Guloglu, Ambulancia SOS, Kola Real y ACHS.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6319\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-19.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6320\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-18.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6321\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-17.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6322\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-16.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6323\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-15.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6324\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-14.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6325\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13-1024x683.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13-1536x1024.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/01\/image_6483441-13.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de la gesti\u00f3n de Corporaci\u00f3n Municipal Costa Chinchorro, el Carnaval Andino con la Fuerza del Sol consigui\u00f3 el aporte de empresas, pymes y emprendedores que asciende a 100 millones de pesos, con lo cual se mejorar\u00e1 la seguridad, difusi\u00f3n y producci\u00f3n. Un total de 41 empresas de alcance local, regional y nacional apoyan&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6321,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"post_folder":[],"class_list":["post-6318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-54","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=6318"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6318\/revisions"}],"predecessor-version":[{"id":6326,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6318\/revisions\/6326"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/6321"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=6318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=6318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=6318"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=6318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}