{"id":6354,"date":"2024-02-28T13:17:48","date_gmt":"2024-02-28T16:17:48","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=6354"},"modified":"2024-02-28T13:17:48","modified_gmt":"2024-02-28T16:17:48","slug":"mas-de-8-toneladas-de-residuos-fueron-recicladas-en-el-carnaval","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/mas-de-8-toneladas-de-residuos-fueron-recicladas-en-el-carnaval\/","title":{"rendered":"M\u00e1s de 8 toneladas de residuos fueron recicladas en el Carnaval"},"content":{"rendered":"<p>La gesti\u00f3n permiti\u00f3 ahorrar 596 litros de agua y evitar que 21 \u00e1rboles se talaran<\/p>\n<p>La empresa gestora de residuos Ambipar-Recynor, la cual fue auspiciadora del Carnaval Andino con la Fuerza del Sol, entreg\u00f3 a los representantes de la Mesa Carnaval un Certificado de trazabilidad de los residuos que se lograron reunir en este evento 2024. Un total de 8.575 kilos de residuos fueron gestionados durante los tres d\u00edas del Carnaval, correspondientes a 1200 kilos de cart\u00f3n, 425 kilos de pl\u00e1stico, 350 kilos de aluminio (latas) y 6600 kilos de vidrio. Estas 8 toneladas de residuos tienen una bioequivalencia correspondiente a 596.586 litros de agua ahorrada, 21 \u00e1rboles sin talar, 29.797 kilowatts sin utilizar o 12.131 emisiones de Co2 sin emitir.<\/p>\n<p>La directora ejecutiva de la Corporaci\u00f3n Municipal Costa Chinchorro, Daniela Ortega Lau destac\u00f3 la alianza p\u00fablico-privada, ya que esto fue posible a trav\u00e9s de 7 puntos limpios que instal\u00f3 Ambipar-Recynor, y 45 monitores de residuos que gestion\u00f3 el Departamento de Medio Ambiente de la Municipalidad de Arica.<\/p>\n<p>\u201cEstamos contentos de que Ambipar-Recynor haya decidido sumarse a los auspiciadores del Carnaval, aportando desde su experiencia en el tema de reciclaje, trabajo que realizamos junto a la oficina de medio ambiente de la Municipalidad de Arica. Desde ya estamos trabajando para continuar y crecer en la recuperaci\u00f3n de residuos para el pr\u00f3ximo Carnaval\u201d.<\/p>\n<p>\u00c1lvaro Valenzuela, gerente general de Ambipar-Recynor, coment\u00f3 que fue un \u201ctremendo privilegio para nosotros entregar un certificado de trazabilidad de los residuos que se recuperaron tales como cart\u00f3n, botellas de vidrio, latas de aluminio y botellas pl\u00e1sticas de bebestible, que en total eran m\u00e1s de 8 toneladas, una cantidad enorme de residuos que pudiesen haber sido m\u00e1s, para nosotros fue importante presentar este certificado de bioequivalencia para generar consciencia\u201d.<\/p>\n<p>Los dirigentes de la Mesa Carnaval coincidieron que estas cifras se pueden seguir mejorando para impulsar la limpieza de la ciudad y el cuidado del medioambiente. Gabriel Mamani, presidente Federaci\u00f3n Kimsa Suyu coment\u00f3 que se trata de n\u00fameros \u201cbien alentadores, es momento de incentivar a las agrupaciones que podamos reciclar nuestra basura y as\u00ed poder tener una ciudad m\u00e1s limpia, cuidar nuestro medio ambiente que es muy importante. En el Carnaval hay harta basura, harta botella, entonces es importante, incluso se convers\u00f3 poder generar puntaje como desaf\u00edo para la limpieza\u201d.<\/p>\n<p>Por su parte, Mart\u00edn Montecinos, presidente Confraternidad de Bailes Andinos, agreg\u00f3 que aumentar estos resultados permitir\u00e1 cuidar a la madre tierra: \u201cHa sido un carnaval con bastantes n\u00fameros que nos invitan a seguir creciendo y fortaleciendo. Estas cifras que nos entrega el auspiciador en cuanto a los resultados de su labor de reciclaje, creemos considerablemente que podemos mejorar estas cifras con el compromiso de todos los bailarines y dirigentes del Carnaval con la fuerza del Sol. Fueron m\u00e1s de 160 toneladas de residuos que se sacaron diariamente, que si logramos aumentar el porcentaje de reciclado sin lugar a dudas estaremos ayudando a nuestra Madre Tierra Pachamama y medio <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6355\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5-300x200.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5-1024x682.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5-768x512.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5-1536x1023.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/02\/image_6487327-5.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>ambiente. Es el compromiso para los pr\u00f3ximos a\u00f1os\u201d, coment\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gesti\u00f3n permiti\u00f3 ahorrar 596 litros de agua y evitar que 21 \u00e1rboles se talaran La empresa gestora de residuos Ambipar-Recynor, la cual fue auspiciadora del Carnaval Andino con la Fuerza del Sol, entreg\u00f3 a los representantes de la Mesa Carnaval un Certificado de trazabilidad de los residuos que se lograron reunir en este evento&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6355,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54],"tags":[],"post_folder":[],"class_list":["post-6354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-54","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=6354"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6354\/revisions"}],"predecessor-version":[{"id":6356,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6354\/revisions\/6356"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/6355"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=6354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=6354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=6354"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=6354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}