{"id":6487,"date":"2024-06-10T13:08:45","date_gmt":"2024-06-10T17:08:45","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=6487"},"modified":"2024-06-10T13:09:41","modified_gmt":"2024-06-10T17:09:41","slug":"empresas-participan-en-taller-de-ecodiseno-para-aplicar-economia-circular","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/empresas-participan-en-taller-de-ecodiseno-para-aplicar-economia-circular\/","title":{"rendered":"Empresas participan en taller de ecodise\u00f1o para aplicar econom\u00eda circular"},"content":{"rendered":"<p>Costa Chinchorro -junto a las empresas Rembre Chile y Cinnda- entrega herramientas a pymes a trav\u00e9s del proyecto \u201cEconom\u00eda circular para la industria agr\u00edcola en Arica\u201d, que apoya Corfo.<\/p>\n<p>Buscando oportunidades para hacer m\u00e1s eficientes sus negocios, cerca de 20 empresas agr\u00edcolas y valorizadoras de residuos participaron del taller de ineficiencias y oportunidades para una industria circular a trav\u00e9s del Programa de Transferencia Tecnol\u00f3gica (PDT) \u201cEconom\u00eda circular para la industria agr\u00edcola en Arica\u201d, ejecutado por la Corporaci\u00f3n Municipal Costa Chinchorro en conjunto con Rembre Chile y Cinnda con el apoyo de Corfo.<\/p>\n<p>La tallerista, la acad\u00e9mica Cecilia Mujica, dise\u00f1adora Industrial de la Universidad de Chile, especialista en Ecodise\u00f1o para una Econom\u00eda Circular, innovaci\u00f3n para la sostenibilidad y Dise\u00f1o con enfoque sist\u00e9mico, con 15 a\u00f1os de experiencia realizando asesor\u00edas y docencia en estas tem\u00e1ticas.<\/p>\n<p>La especialista explic\u00f3 que el taller trat\u00f3 de principios b\u00e1sicos de la econom\u00eda circular y conceptos clave del ecodise\u00f1o y el objetivo era poder visualizar oportunidades de eficiencia y circularidad en la industria agr\u00edcola de la regi\u00f3n. \u201cLa recepci\u00f3n del taller me pareci\u00f3 incre\u00edble, estuvieron muy participativos, muy atentos, identificaron muchas oportunidades que pueden ser transformadas en posibilidad de mejorar la relaci\u00f3n que la industria y la regi\u00f3n tienen con los residuos pl\u00e1sticos. Creo que fue a nivel humano super grata experiencia, la energ\u00eda de las personas y el inter\u00e9s en las tem\u00e1ticas, espero que se pueda transformar en algo de valor para ellos en el futuro\u201d.<\/p>\n<p>Michelle Ponce, gerenta de innovaci\u00f3n en Hidropon\u00eda Mallkivitor, dijo estar entusiasmada de participar en este taller. \u201cEs un tema emergente, es necesario poder revalorizar, poder transformar procesos productivos. Estamos en esta iniciativa de poder cambiar completamente el enfoque de producci\u00f3n agr\u00edcola y para all\u00e1 vamos. Nosotros somos hidropon\u00eda, hacemos otro tipo de agricultura que no es convencional ni tradicional aqu\u00ed. Estamos contentos de generar v\u00ednculos en el taller, todos estamos viendo como poder reutilizar, reciclar y valorizar\u201d.<\/p>\n<p>Sebasti\u00e1n Vildoso, integrante del equipo de la empresa Solar Trust, coment\u00f3 que fue una buena experiencia. \u201cNuestra empresa est\u00e1 reciclando y valorizando paneles fotovoltaicos y esta charla trataba sobre los sectores agr\u00edcolas, donde tambi\u00e9n participa nuestra empresa a trav\u00e9s de un proyecto nuevo. Enfocar este concepto abre una nueva perspectiva para desarrollar nuevos productos con la mirada del ecodise\u00f1o, diferentes estrategias y maneras de abordar las problem\u00e1ticas. Adem\u00e1s, compartir con diferentes entornos del ecosistema estuvo muy bueno porque as\u00ed nos vincula con las diferentes personas para potenciar este<br \/>\ncamino\u201d.<\/p>\n<p>A trav\u00e9s de este PDT \u201cEconom\u00eda circular para la industria agr\u00edcola en Arica\u201d, Costa Chinchorro realizar\u00e1 un total de seis talleres y charlas de especialistas en la transici\u00f3n hacia la econom\u00eda circular y aplicaci\u00f3n de la Ley REP. Entre los expertos, vendr\u00e1 un especialista de Espa\u00f1a, quien visitar\u00e1 a las empresas beneficiarias del proyecto.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6488\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-300x225.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-1024x768.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-768x576.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-1536x1152.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50737153-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6489\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-300x225.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-1024x768.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-768x576.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-1536x1152.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/06\/image_50402817-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Costa Chinchorro -junto a las empresas Rembre Chile y Cinnda- entrega herramientas a pymes a trav\u00e9s del proyecto \u201cEconom\u00eda circular para la industria agr\u00edcola en Arica\u201d, que apoya Corfo. Buscando oportunidades para hacer m\u00e1s eficientes sus negocios, cerca de 20 empresas agr\u00edcolas y valorizadoras de residuos participaron del taller de ineficiencias y oportunidades para una&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,1],"tags":[],"post_folder":[],"class_list":["post-6487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias","category-54","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=6487"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6487\/revisions"}],"predecessor-version":[{"id":6493,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6487\/revisions\/6493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/6488"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=6487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=6487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=6487"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=6487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}