{"id":6753,"date":"2024-08-01T14:45:52","date_gmt":"2024-08-01T18:45:52","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=6753"},"modified":"2024-08-01T14:45:52","modified_gmt":"2024-08-01T18:45:52","slug":"sergi-arola-tomas-olivera-y-chefs-de-peru-y-bolivia-seran-parte-de-carnaval-de-sabores-2024","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/sergi-arola-tomas-olivera-y-chefs-de-peru-y-bolivia-seran-parte-de-carnaval-de-sabores-2024\/","title":{"rendered":"Sergi Arola, Tomas Olivera y chefs de Per\u00fa y Bolivia ser\u00e1n parte de Carnaval de Sabores 2024"},"content":{"rendered":"<p style=\"text-align: center;\"><em>42 empresas gastron\u00f3micas presentes este 3 y 4 de agosto en el Parque Centenario<\/em><\/p>\n<p style=\"text-align: left;\">Con la frases \u201cJuntando Hambre\u201d y \u201cGuatita Llena, coraz\u00f3n contento\u201d se lanz\u00f3 oficialmente la octava versi\u00f3n de Carnaval de Sabores, el evento gastron\u00f3mico m\u00e1s importante de Arica, organizado por Corporaci\u00f3n Municipal Costa Chinchorro, Inacap y Municipalidad de Arica.<\/p>\n<p style=\"text-align: left;\">El evento que en 2023 reuni\u00f3 a m\u00e1s de 25 mil comensales, este a\u00f1o parte con una proyecci\u00f3n internacional con la participaci\u00f3n del chef espa\u00f1ol Sergi Arola, la chef boliviana Coral Ayoroa, y el Chef peruano Pedro Miguel Schiaffino. Los chef internacionales compartir\u00e1n escenario con el nacional Tom\u00e1s Olivera de \u201cSabor a gol\u201d y Alejandra Toloza, pionera en la profesionalizaci\u00f3n de la cocina vegana. A nivel local estar\u00e1n Alexa Gallardo de Akapacha, Ricardo P\u00e9rez de La Chimba, y Luis Valenzuela de LV Chocolatier.<\/p>\n<p style=\"text-align: left;\">El alcalde de Arica y presidente del directorio de la Corporaci\u00f3n Municipal Costa Chinchorro, Gerardo Esp\u00edndola Rojas, coment\u00f3 que esta actividad se enmarca en los seis a\u00f1os de recuperaci\u00f3n del Parque Centenario y se proyecta como una inyecci\u00f3n para la econom\u00eda.<\/p>\n<p style=\"text-align: left;\">\u201cLo que comenz\u00f3 como una actividad peque\u00f1a cuando se une Inacap con Costa Chinchorro comenz\u00f3 a crecer, sobrevivi\u00f3 a la Pandemia, y hoy se posiciona como la fiesta gastron\u00f3mica m\u00e1s importante del norte del pa\u00eds. Invitamos a todos a juntar hambre, juntar dinero porque esta es una inyecci\u00f3n a la econom\u00eda local, a los emprendedores locales, restaurantes y cocineros\u201d, dijo la autoridad comunal.<\/p>\n<p style=\"text-align: left;\">El vicerrector de Inacap, Daniel Uribe, relev\u00f3 esta alianza que ha permitido hacer crecer el carnaval de Sabores y que hoy ya inici\u00f3 su proceso de internacionalizaci\u00f3n. \u201cSeguimos proyect\u00e1ndonos y esperamos en una pr\u00f3xima versi\u00f3n superar la barrera de las 50 mil personas\u201d.<\/p>\n<p style=\"text-align: left;\">La directora ejecutiva de Costa Chinchorro, Daniela Ortega destac\u00f3 la participaci\u00f3n de emprendimientos y empresas gastron\u00f3micas: \u201cEsta vez son 75 emprendimientos y empresas gastron\u00f3micas. Tendremos 42 restaurantes, adem\u00e1s de artesanos y emporios, porque la idea es relevar y conocer los productos que se producen en nuestra ciudad. Llevamos meses trabajando en esto porque nos interesa que este evento crezca, que sea un evento tur\u00edstico donde todo el mundo nos reconozca\u201d.<\/p>\n<p style=\"text-align: left;\">Por su parte, la chef y directora de la carrera de turismo y gastronom\u00eda de Inacap sede Arica, Claudia Valdivia Palacios invit\u00f3 a la comunidad a disfrutar de los destacados invitados de este a\u00f1o.<\/p>\n<p style=\"text-align: left;\">\u201cVamos a estar con grandes chef locales, nacionales e internacionales. El s\u00e1bado 3 estaremos con Coral Ayoroa que es una chef top\u00edsima, masterchef Bolivia; con Ale Toloza, que es una chef de la tendencia <em>plant based<\/em> para todas las personas que no consumen animales. Tambi\u00e9n estar\u00e1 Tom\u00e1s Olivera, quien va a parrillar en Carnaval de Sabores, con Sergi Arola, y Pedro Miguel Schiaffino, \u00edcono de la cocina peruana, son un lujo de invitados, as\u00ed que no se pueden perder la octava versi\u00f3n de Carnaval de Sabores\u201d.<\/p>\n<p>El lanzamiento tuvo la participaci\u00f3n de los concejales Jorge Mollo, Max Schauer, Mario Mamani y Gabriel Fern\u00e1ndez Canque; los directores de la Corporaci\u00f3n Municipal, Cristian Leiva y Gonzalo Ramos, Seremi de Econom\u00eda, director de Sernatur, C\u00e1mara Chilena de la Construcci\u00f3n, C\u00e1mara de Comercio; y la empresa gastron\u00f3mica El Chal\u00e1n. Este a\u00f1o Carnaval de Sabores cuenta con el auspicio de Hotel Arica, Cargo Arica, Aguas del Altiplano, Varos Restoran, Benexia y Madero.<\/p>\n<p>El Carnaval de Sabores se realizar\u00e1 el 3 y 4 de agosto en el Parque Centenario de 11:00 a 18:30 horas, la entrada es liberada y los 42 restaurantes tendr\u00e1n plantos desde los $4.500.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6757\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3-300x200.jpeg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3-1024x682.jpeg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3-768x512.jpeg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3-1536x1023.jpeg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-3.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6756\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5-300x200.jpeg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5-1024x682.jpeg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5-768x512.jpeg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5-1536x1023.jpeg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-5.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6755\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2-300x200.jpeg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2-1024x682.jpeg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2-768x512.jpeg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2-1536x1023.jpeg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamiento-2.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-6754\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1-300x200.jpeg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1-1024x682.jpeg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1-768x512.jpeg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1-1536x1023.jpeg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/08\/cds-2024-lanzamieto-1.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>42 empresas gastron\u00f3micas presentes este 3 y 4 de agosto en el Parque Centenario Con la frases \u201cJuntando Hambre\u201d y \u201cGuatita Llena, coraz\u00f3n contento\u201d se lanz\u00f3 oficialmente la octava versi\u00f3n de Carnaval de Sabores, el evento gastron\u00f3mico m\u00e1s importante de Arica, organizado por Corporaci\u00f3n Municipal Costa Chinchorro, Inacap y Municipalidad de Arica. El evento que&hellip;<\/p>\n","protected":false},"author":2,"featured_media":6757,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,1],"tags":[],"post_folder":[],"class_list":["post-6753","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias","category-54","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=6753"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6753\/revisions"}],"predecessor-version":[{"id":6758,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/6753\/revisions\/6758"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/6757"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=6753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=6753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=6753"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=6753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}