{"id":7030,"date":"2024-11-11T10:39:43","date_gmt":"2024-11-11T13:39:43","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=7030"},"modified":"2024-11-11T10:39:43","modified_gmt":"2024-11-11T13:39:43","slug":"agricultores-fortalecen-sus-negocios-con-economia-circular","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/agricultores-fortalecen-sus-negocios-con-economia-circular\/","title":{"rendered":"Agricultores fortalecen sus negocios con econom\u00eda circular"},"content":{"rendered":"<p style=\"text-align: center;\"><em>Los exitosos resultados son parte del Programa de Difusi\u00f3n Tecnol\u00f3gica (PDT) apoyado por Corfo y ejecutado por la Corporaci\u00f3n Municipal Costa Chinchorro junto a Rembre y Cinnda.<\/em><\/p>\n<p>Una nueva empresa valorizadora de cintas de riego para crear madera pl\u00e1stica, negocios entre empresas agr\u00edcolas y recicladores, el dise\u00f1o de una planta de reciclaje para el Valle de Azapa y mayor conocimiento para fortalecer tanto la producci\u00f3n como la venta de productos agr\u00edcolas. Fueron parte de los resultados del Programa de Difusi\u00f3n Tecnol\u00f3gica (PDT) \u201cEconom\u00eda Circular para el \u00e1rea Agr\u00edcola para la comuna de Arica\u201d apoyado por Corfo y ejecutado por la Corporaci\u00f3n Municipal Costa Chinchorro junto a Rembre y Cinnda.<\/p>\n<p>Estos resultados fueron presentados en el seminario de cierre \u201cExperiencias de Espa\u00f1a y Argentina para la Agricultura sostenible en Arica\u201d, en el que participaron los especialistas Diego Teruel, director de Negocios del Centro Tecnol\u00f3gico Nacional de la Industria Auxiliar de la Agricultura, Tecnova, en Almer\u00eda, quien visit\u00f3 la regi\u00f3n y se reuni\u00f3 con beneficiarios del proyecto para asesorarlos; y con Jos\u00e9 Risso Cardo, director t\u00e9cnico de Desarrollo de Equipos Industriales DEISA en Argentina, quien con los datos levantados por el proyecto dise\u00f1\u00f3 una planta de reciclaje para el Valle de Azapa.<\/p>\n<p>El presidente de la Corporaci\u00f3n Municipal y alcalde de Arica, Gerardo Esp\u00edndola Rojas, destac\u00f3 esta iniciativa para transitar hacia una agricultura m\u00e1s sustentable: \u201cA trav\u00e9s de nuestra Corporaci\u00f3n Costa Chinchorro, junto con la Corfo, generamos este PDT que se hace cargo de tomar los residuos inorg\u00e1nicos de los valles y transformarlos, no solo en un desecho, sino que transformarlos en materia prima para generar otro tipo de insumos, por lo que se trata de avanzar hacia la econom\u00eda circular\u201d, expres\u00f3.<\/p>\n<p>Luis Rocafull L\u00f3pez, director regional Corfo, explic\u00f3 que la asociatividad genera una gran oportunidad para el manejo de residuos agr\u00edcolas. \u201cLa agricultura aparte de sembrar y cosechar productos, tambi\u00e9n nos genera una oportunidad de poder aprovechar los residuos, principalmente pl\u00e1sticos y en asociatividad con Costa Chinchorro aportamos recursos en dialogar, conversar, internalizar y difundir que este tipo de tecnolog\u00edas s\u00ed son aplicables y que verdaderamente pueden ser parte del desarrollo econ\u00f3mico de nuestra regi\u00f3n\u201d.<\/p>\n<p>Este conocimiento traspasado ha sido provechoso para los agricultores participantes porque les permite agregar valor a su modelo de negocios y as\u00ed participar en nuevos mercados como los supermercados, donde les exigen certificados de valorizaci\u00f3n de residuos. As\u00ed lo coment\u00f3 el administrador de la parcela de Roxana Gardilcic, Juan Venegas, quien explic\u00f3 que tambi\u00e9n estos conocimientos le permiten tener m\u00e1s ordenado el espacio.<\/p>\n<p>\u201cEl programa nos ayud\u00f3 a comercializar nuestros productos, porque quienes nos compran nos exigen el manejo de residuos. Lo mejor es que nos est\u00e1 dando muy buenos resultados y quienes nos visitan quedan encantados y nos felicitan por lo limpia que tenemos la parcela\u201d, cont\u00f3 Venegas.<\/p>\n<p>En el proyecto tambi\u00e9n participaron empresas que est\u00e1n valorizando residuos como lo es North Clothes, donde reciclan textiles. Jorge Tapia, su administrador relev\u00f3 la incorporaci\u00f3n de conocimiento sobre la Ley REP: \u201cMe pareci\u00f3 s\u00faper interesante, eran cosas que no manejaba. Entonces nunca se termina de aprender. Como empresa estamos muy involucrados en el tema del reciclaje en el \u00e1rea agr\u00edcola. Nos abri\u00f3 la mente para nuevas ideas, as\u00ed que felicito a la gente que tiene que ver con este programa, que es muy interesante y se aprenden cosas nuevas que nos van a servir mucho en el desarrollo de nuestros procesos productivos\u201d.<\/p>\n<p>El expositor Diego Teruel, destac\u00f3 el camino que hay que seguir para avanzar a una agricultura 2.0: \u201cDesde Espa\u00f1a estamos transfiriendo conocimiento, que tenemos de c\u00f3mo gestionamos los residuos, de cu\u00e1les fueron nuestras problem\u00e1ticas por no hacerlo al inicio y que al final esto trae una producci\u00f3n y un tipo de agricultura m\u00e1s sostenible, con una mejor marca a nivel exterior y mejor reconocimiento de que se est\u00e1n haciendo las cosas bien\u201d.<\/p>\n<p>A partir de la problem\u00e1tica de la alta producci\u00f3n de residuos en los valles de Arica, los cuales en muchas ocasiones terminaban en el lecho del r\u00edo y finalmente en el mar, se decidi\u00f3 realizar este proyecto que permiti\u00f3 traspasar conocimiento a 18 empresas de la comuna en torno a la econom\u00eda circular. Todos los resultados, el dise\u00f1o de una planta de reciclaje y fichas informativas sobre c\u00f3mo reciclar residuos agr\u00edcolas estar\u00e1n disponibles en un repositorio en la p\u00e1gina web de la Corporaci\u00f3n Municipal Costa Chinchorro para que toda la comunidad pueda acceder.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7031\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-25-225x300.jpg\" alt=\"\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-25-225x300.jpg 225w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-25-768x1024.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-25-1152x1536.jpg 1152w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-25.jpg 1200w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/> \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7032\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-300x225.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-1024x768.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-768x576.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-1536x1152.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50428673-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7033\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-22-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-22-212x300.jpg 212w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-22-722x1024.jpg 722w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-22.jpg 749w\" sizes=\"auto, (max-width: 212px) 100vw, 212px\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7034\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-21-211x300.jpg\" alt=\"\" width=\"211\" height=\"300\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-21-211x300.jpg 211w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-21-722x1024.jpg 722w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6487327-21.jpg 749w\" sizes=\"auto, (max-width: 211px) 100vw, 211px\" \/>\u00a0 \u00a0 <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7035\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-300x225.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-1024x768.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-768x576.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-1536x1152.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_50432769-2048x1536.jpg 2048w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>\u00a0 \u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-7036\" src=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24-300x225.jpg 300w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24-1024x768.jpg 1024w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24-768x576.jpg 768w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24-1536x1152.jpg 1536w, https:\/\/www.costachinchorro.cl\/ccc23\/wp-content\/uploads\/2024\/11\/image_6483441-24.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los exitosos resultados son parte del Programa de Difusi\u00f3n Tecnol\u00f3gica (PDT) apoyado por Corfo y ejecutado por la Corporaci\u00f3n Municipal Costa Chinchorro junto a Rembre y Cinnda. Una nueva empresa valorizadora de cintas de riego para crear madera pl\u00e1stica, negocios entre empresas agr\u00edcolas y recicladores, el dise\u00f1o de una planta de reciclaje para el Valle&hellip;<\/p>\n","protected":false},"author":2,"featured_media":7037,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,1],"tags":[],"post_folder":[],"class_list":["post-7030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias","category-54","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/7030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=7030"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/7030\/revisions"}],"predecessor-version":[{"id":7038,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/7030\/revisions\/7038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/7037"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=7030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=7030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=7030"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=7030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}