{"id":8701,"date":"2026-01-26T09:07:12","date_gmt":"2026-01-26T12:07:12","guid":{"rendered":"https:\/\/www.costachinchorro.cl\/?p=8701"},"modified":"2026-01-26T09:07:12","modified_gmt":"2026-01-26T12:07:12","slug":"empresas-locales-se-la-juegan-por-arica-costa-chinchorro-gestiona-200-millones-de-pesos-para-el-carnaval","status":"publish","type":"post","link":"https:\/\/www.costachinchorro.cl\/ccc23\/empresas-locales-se-la-juegan-por-arica-costa-chinchorro-gestiona-200-millones-de-pesos-para-el-carnaval\/","title":{"rendered":"\u00a1Empresas locales se la juegan por Arica! \u201cCosta Chinchorro\u201d gestiona 200 millones de pesos para el Carnaval"},"content":{"rendered":"<p><em><strong>En la entrega del Sello Carnaval, el alcalde Orlando Vargas destac\u00f3 el aporte del mundo privado.<\/strong><\/em><\/p>\n<p>En tiempos de\u00a0carnaval\u00a0los\u00a0empresarios locales\u00a0demuestran el amor que sienten por\u00a0Arica. Hab\u00eda que empujar el carro, y de inmediato el mundo privado dijo presente con\u00a0200 millones de pesos\u00a0que se sumar\u00e1n a los esfuerzos que realiza la\u00a0Corporaci\u00f3n \u201cCosta Chinchorro\u201d\u00a0y la\u00a0Municipalidad de Arica.<\/p>\n<p>\u201cPara nosotros como Mesa Carnaval los auspiciadores tienen una tremenda importancia. Quiero felicitarlos por su disposici\u00f3n y porque piensan en Arica como nosotros\u201d,\u00a0dijo el alcalde Orlando Vargas.<\/p>\n<p>\u201cEstas empresas han aportado cerca del 20 por ciento de los gastos generales del carnaval. Son aportes por m\u00e1s de 200 millones de pesos que ser\u00e1n invertidos directamente en el carnaval,\u00a0destac\u00f3 el director ejecutivo de \u201cCosta Chinchorro\u201d, Juan Jos\u00e9 Araya.<\/p>\n<p><strong>Empresas arique\u00f1as<\/strong><\/p>\n<p>Asimismo, Araya dijo que\u00a0\u201cm\u00e1s de sesenta empresas arique\u00f1as est\u00e1n apoyando nuestro carnaval. Estamos muy agradecidos por el apoyo que nos ha entregado el mundo privado\u201d.<\/p>\n<p>Para el director ejecutivo de Costa Chinchorro es importante recalcar que\u00a0\u201cm\u00e1s del sesenta por ciento son peque\u00f1as empresas que han querido colaborar en la puesta en escena del carnaval 2026\u201d.<\/p>\n<p><strong>Agradecimientos<\/strong><\/p>\n<p>\u201cQuiero agradecer el trabajo de la Corporaci\u00f3n y a todos los auspiciadores que est\u00e1n poniendo grano de arena para que este carnaval sea uno de los m\u00e1s importantes de los \u00faltimos a\u00f1os\u201d,\u00a0indic\u00f3 el presidente de la Confraternidad de Bailes Andinos \u201cInti Chamampi\u201d, Mart\u00edn Romero.<\/p>\n<p>Al igual que su colega Romero, el presidente de Federaci\u00f3n de la Cultura y las Artes Ind\u00edgenas \u201cKimsa Suyu\u201d, Gabriel Mamani, destac\u00f3 el trabajo de Costa Chinchorro y de paso invit\u00f3\u00a0a las empresas a que se sigan sumando a la celebraci\u00f3n del Carnaval Andino \u201cArica Con la Fuerza del Sol\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En la entrega del Sello Carnaval, el alcalde Orlando Vargas destac\u00f3 el aporte del mundo privado. En tiempos de\u00a0carnaval\u00a0los\u00a0empresarios locales\u00a0demuestran el amor que sienten por\u00a0Arica. Hab\u00eda que empujar el carro, y de inmediato el mundo privado dijo presente con\u00a0200 millones de pesos\u00a0que se sumar\u00e1n a los esfuerzos que realiza la\u00a0Corporaci\u00f3n \u201cCosta Chinchorro\u201d\u00a0y la\u00a0Municipalidad de Arica.&hellip;<\/p>\n","protected":false},"author":2,"featured_media":8702,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[54,1],"tags":[],"post_folder":[],"class_list":["post-8701","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-noticias","category-54","category-1","description-off"],"_links":{"self":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/8701","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/comments?post=8701"}],"version-history":[{"count":1,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/8701\/revisions"}],"predecessor-version":[{"id":8703,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/posts\/8701\/revisions\/8703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media\/8702"}],"wp:attachment":[{"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/media?parent=8701"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/categories?post=8701"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/tags?post=8701"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.costachinchorro.cl\/ccc23\/wp-json\/wp\/v2\/post_folder?post=8701"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}